{"id":11526,"date":"2021-01-04T10:05:17","date_gmt":"2021-01-04T09:05:17","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=11526"},"modified":"2021-01-22T11:08:24","modified_gmt":"2021-01-22T10:08:24","slug":"ex-fornace-di-riccione","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/","title":{"rendered":"Ex-fornace di Riccione: Il calore del colore"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nella categoria Interventi di Riqualificazione Edilizia, la giuria dei<br>Premi In\/Architettura 2020 ha deciso di assegnare una &#8220;Menzione Speciale\u201d all\u2019opera: <strong><em>Recupero della ex-fornace di Riccione, Pietro Carlo Pellegrini<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"90\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/MLG-20-PREMIO-INARCH-copia.svg\" alt=\"\" class=\"wp-image-11282\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Committente: Comune di Riccione<br>Progettisti: Pietro Carlo Pellegrini<br>Impresa: UNIECO soc. coop.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019architettura pu\u00f2 essere fuoco, o nascere dal fuoco, e rimanere tale dopo essere stata trasformata dalla cottura dell\u2019argilla in forma, in spazio, in un altro pezzo di citt\u00e0, ci vuole la sapienza antica dei maestri per renderla attuale attraverso l\u2019azione ferma e coerente di un grande architetto, e <strong>Pellegrini<\/strong> \u00e8 tutto questo, perch\u00e9 riassume la forza rinascimentale con lo slancio della contemporaneit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La scelta dei materiali, e del materiale principe raddoppia la difficolt\u00e0 del progettista per piegare alle esigenze della sua polimorfa idealit\u00e0 il volume, i volumi finali, senza rinunciare mai allo scopo al principio che pone l\u2019artefice come sommo responsabile etico dell\u2019estetica della sua opera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Una sfida culturale<\/strong> che Pellegrini supera con leggerezza mantenendo la profondit\u00e0 del pensiero generatore, da una fornace attiva, <strong>la trasformazione di un ex-fornace<\/strong>, mattone, sopra il mattone, colore rosso sopra l\u2019ocra, e il risultato <strong>mantiene intatto il calore dell\u2019emozione in tutta la profondit\u00e0 del suo significato.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"811\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_6-811x1024.jpg\" alt=\"ex-fornace di Riccione, Pier Carlo Pellegrini\" class=\"wp-image-11533\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_6-811x1024.jpg 811w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_6-238x300.jpg 238w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_6-768x970.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_6-396x500.jpg 396w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_6.jpg 855w\" sizes=\"auto, (max-width: 811px) 100vw, 811px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Non \u00e8 una sorpresa nell\u2019Opera di Pellegrini che da tanti anni incastona nel paesaggio italiano pietre preziose e forme indimenticabili dove ogni particolare vive la sua utilit\u00e0 in relazione alla complessit\u00e0 delle inter-relazioni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/memoriale-della-shoah-milano\/\">Memoriale della Shoah di Milano: In\/Arch premia lo Studio Morpurgo De Curtis<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In questo caso le nuove funzioni si adattano in maniera talentuosa all\u2019interno dell\u2019antico spazio di lavoro (1908), creando occasioni di scambio tra la riqualificazione della citt\u00e0 attraverso momenti di incontro e di socializzazione e la costruzione di una nuova scuola e del Teatro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La materia antica, il mattone in questa architettura esprime la luce pi\u00f9 pura, crea il dialogo vivo e attuale tra passato e futuro, in una sequenza indistinta dove la storia evolve, e la quotidianit\u00e0 si trasforma all\u2019interno del nuovo spazio pubblico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"868\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_2-1024x868.jpg\" alt=\"ex-fornace di Riccione, Pier Carlo Pellegrini\" class=\"wp-image-11536\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_2-1024x868.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_2-300x254.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_2-768x651.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_2-500x424.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_2.jpg 1274w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pellegrini rivaluta metaforicamente la materia originaria, ne stabilisce un nuovo \u201cinizio\u201d dando spazio alla capacit\u00e0 di una passione estetica mai sopita nel tempo, tutto in questo progetto articolato si pu\u00f2 leggere dal \u201cprima al dopo\u201d, e viceversa, ed \u00e8 l\u2019atteggiamento corretto che l\u2019artefice deve mantenere affinch\u00e9 l\u2019architettura risulti padrona del proprio tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Menzione meritata perch\u00e9 stabilisce un principio inalienabile della qualit\u00e0 della bellezza, quella autonomia scevra da percorsi \u201calla moda\u201d, che caratterizzano tutte le evoluzioni stilistiche di vera densit\u00e0 culturale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un approdo sicuro nella convulsa ricerca del \u201ccalore contemporaneo\u201d, quel colore cos\u00ec marcato che rende deciso il racconto che anche questa volta Pellegrini ha voluto regalarci, e per questo non possiamo che ringraziarlo, come abitanti di citt\u00e0 e come critici.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"552\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_3-1024x552.jpg\" alt=\"ex-fornace di Riccione, Pier Carlo Pellegrini\" class=\"wp-image-11538\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_3-1024x552.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_3-300x162.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_3-768x414.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_3-1536x828.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_3-500x270.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">(Il progetto riguarda il recupero della <strong>ex-Fornace di Riccione<\/strong>, complesso industriale adibito alla produzione di laterizi, costruito nel 1908 e dismesso nel 1970. L\u2019area complessiva di intervento misura mq. 40.000; la superficie coperta \u00e8 di mq. 3.400 totali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/lavazza-headquarters-cino-zucchi\/\">Lavazza Headquarters \u2013 con Cino Zucchi \u2013 vince il premio In\/Architettura 2020<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le vecchie destinazioni lasciano posto alle nuove, sfruttando le possibilit\u00e0 spaziali dei vecchi corpi di fabbrica, che mantengono cos\u00ec le loro forme, memoria storica del luogo: nei corpi di fabbrica troveranno posto una Scuola Media di 18 classi per un totale di 450 alunni, un Teatro multifunzionale da 650 posti, una sede ad Uffici, oltre alla sistemazione degli spazi esterni. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"943\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_5-1024x943.jpg\" alt=\"ex-fornace di Riccione, Pier Carlo Pellegrini\" class=\"wp-image-11540\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_5-1024x943.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_5-300x276.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_5-768x707.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_5-500x460.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Ex-fornace_Riccione_onelistonegiordano_5.jpg 1173w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cPer questa volta volevo fare giustizia dell\u2019odio per il meraviglioso che imperversa in certi uomini, del ridicolo sotto il quale vogliono farlo cadere. Parliamo chiaro: il meraviglioso \u00e8 sempre bello, qualsiasi meraviglioso \u00e8 bello, anzi non c\u2019\u00e8 nient\u2019altro di bello che il meraviglioso\u201d<\/em><\/p><cite><strong>Andre Breton, Manifesti del Surrealismo, intr. Di G. Neri, trad. di L. Magrini, Einaudi, Torino 1966.<\/strong><\/cite><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/lavazza-headquarters-cino-zucchi\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/LAVAZZA_one_ListoneGiordano_1-500x312.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/lavazza-headquarters-cino-zucchi\/\" rel=\"bookmark\">Lavazza Headquarters \u2013 con Cino Zucchi &#8211; vince il premio In\/Architettura 2020<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/museo-degli-innocenti\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Museo-degli-Innocenti_one_Listone-Giordano_4-500x241.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/\">Maurizio De Caro<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/museo-degli-innocenti\/\" rel=\"bookmark\">Nel silenzio del Museo degli Innocenti<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/alessandro-bulletti\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/10\/CK_06-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/alessandro-bulletti\/\" rel=\"bookmark\">Casa K, a firma Alessandro Bulletti Architetti, vince il premio speciale IN\/ARCH.<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/memoriale-della-shoah-milano\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/12\/Memoriale_Shoah_Milano_One_ListoneGiordano_1-500x327.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/memoriale-della-shoah-milano\/\" rel=\"bookmark\">Memoriale della Shoah di Milano: In\/Arch premia lo Studio Morpurgo De Curtis<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nella categoria Interventi di Riqualificazione Edilizia, la giuria deiPremi In\/Architettura 2020 ha deciso di assegnare una &#8220;Menzione Speciale\u201d all\u2019opera: Recupero [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":12116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-11526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/fornace.riccione.museo_.territorio.06-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ex-fornace di Riccione: Il calore del colore | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"In\/Architettura 2020 ha deciso di assegnare una &quot;Menzione Speciale\u201d all\u2019opera: Recupero della ex-fornace di Riccione, Pier Carlo Pellegrini.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex-fornace di Riccione: Il calore del colore\" \/>\n<meta property=\"og:description\" content=\"Nella categoria Interventi di Riqualificazione Edilizia, la giuria deiPremi In\/Architettura 2020 ha deciso di assegnare una &quot;Menzione Speciale\u201d all\u2019opera:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-04T09:05:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-22T10:08:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/fornace.riccione.museo_.territorio.06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"845\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maurizio De Caro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maurizio De Caro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/\"},\"author\":{\"name\":\"Maurizio De Caro\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\"},\"headline\":\"Ex-fornace di Riccione: Il calore del colore\",\"datePublished\":\"2021-01-04T09:05:17+00:00\",\"dateModified\":\"2021-01-22T10:08:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/\"},\"wordCount\":622,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/fornace.riccione.museo_.territorio.06.jpg\",\"articleSection\":[\"Architettura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/\",\"name\":\"Ex-fornace di Riccione: Il calore del colore | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/fornace.riccione.museo_.territorio.06.jpg\",\"datePublished\":\"2021-01-04T09:05:17+00:00\",\"dateModified\":\"2021-01-22T10:08:24+00:00\",\"description\":\"In\\\/Architettura 2020 ha deciso di assegnare una \\\"Menzione Speciale\u201d all\u2019opera: Recupero della ex-fornace di Riccione, Pier Carlo Pellegrini.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/fornace.riccione.museo_.territorio.06.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/fornace.riccione.museo_.territorio.06.jpg\",\"width\":1200,\"height\":845,\"caption\":\"ex fornace riccione\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/ex-fornace-di-riccione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex-fornace di Riccione: Il calore del colore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\",\"name\":\"Maurizio De Caro\",\"description\":\"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\\\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/decaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ex-fornace di Riccione: Il calore del colore | One Listone Giordano","description":"In\/Architettura 2020 ha deciso di assegnare una \"Menzione Speciale\u201d all\u2019opera: Recupero della ex-fornace di Riccione, Pier Carlo Pellegrini.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/","og_locale":"it_IT","og_type":"article","og_title":"Ex-fornace di Riccione: Il calore del colore","og_description":"Nella categoria Interventi di Riqualificazione Edilizia, la giuria deiPremi In\/Architettura 2020 ha deciso di assegnare una \"Menzione Speciale\u201d all\u2019opera:","og_url":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2021-01-04T09:05:17+00:00","article_modified_time":"2021-01-22T10:08:24+00:00","og_image":[{"width":1200,"height":845,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/fornace.riccione.museo_.territorio.06.jpg","type":"image\/jpeg"}],"author":"Maurizio De Caro","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maurizio De Caro","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/"},"author":{"name":"Maurizio De Caro","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481"},"headline":"Ex-fornace di Riccione: Il calore del colore","datePublished":"2021-01-04T09:05:17+00:00","dateModified":"2021-01-22T10:08:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/"},"wordCount":622,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/fornace.riccione.museo_.territorio.06.jpg","articleSection":["Architettura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/","url":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/","name":"Ex-fornace di Riccione: Il calore del colore | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/fornace.riccione.museo_.territorio.06.jpg","datePublished":"2021-01-04T09:05:17+00:00","dateModified":"2021-01-22T10:08:24+00:00","description":"In\/Architettura 2020 ha deciso di assegnare una \"Menzione Speciale\u201d all\u2019opera: Recupero della ex-fornace di Riccione, Pier Carlo Pellegrini.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/fornace.riccione.museo_.territorio.06.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/fornace.riccione.museo_.territorio.06.jpg","width":1200,"height":845,"caption":"ex fornace riccione"},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/ex-fornace-di-riccione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Ex-fornace di Riccione: Il calore del colore"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481","name":"Maurizio De Caro","description":"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net","url":"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/11526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=11526"}],"version-history":[{"count":12,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/11526\/revisions"}],"predecessor-version":[{"id":11628,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/11526\/revisions\/11628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/12116"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=11526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=11526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=11526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}