{"id":12341,"date":"2021-02-15T12:36:11","date_gmt":"2021-02-15T11:36:11","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=12341"},"modified":"2021-03-05T12:16:23","modified_gmt":"2021-03-05T11:16:23","slug":"40-bleecker-street-new-york","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/","title":{"rendered":"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Svelato a NoHo&nbsp;<strong>40 Bleecker street<\/strong>; il nuovo progetto residenziale di lusso a <strong>New York<\/strong> riporta in vita un pezzo di storia centenaria, a pochi passi dall\u2019energia di Soho e dalle vibrazioni artistiche dell\u2019East Village.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una curiosit\u00e0 sull&#8217;origine toponomastica: fu la famiglia Bleeckers &#8211; che possedeva una fattoria in quella zona&nbsp; &#8211; a dare il suo nome alla strada ad inizio &#8216;800.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-24.jpg\" alt=\"40 Bleecker street new york\" class=\"wp-image-12351\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-24.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-24-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-24-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un edificio recuperato da <a href=\"http:\/\/www.rawlingsarchitects.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rawlings Architects<\/a><\/strong>, insieme al famoso paesaggista <strong>Edmund Hollander<\/strong>, che ha scolpito il giardino segreto con piante, cascate zen e sentieri rigorosi-  l&#8217;interior \u00e8 firmato da <strong>Ryan Korban<\/strong> (nella lista dei top 100 designer stilata dalla rivista AD). &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un progetto in grande scala &#8211; dotato di servizi esclusivi ed aree comuni di grande fascino tra cui piscina e palestra privata, negozi dedicati e ristorante- &nbsp;capace di rivitalizzare uno storico edificio dalle caratteristiche distintive. Le inconfondibili linee curve della facciata e l\u2019ordine di finestre composto in una precisa griglia geometrica, <strong>dalle quali si gode una spettacolare vista di Manhattan<\/strong>, incontrano il tratto del design moderno.&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/ise-frank-gropius\/\">L\u2019amore, il sogno e la storia tra Ise Frank e Walter Gropius<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli interni, curati personalmente da <strong>Ryan Korban<\/strong>, prediligono materiali naturali e di nobile discendenza: <strong>dai pregiati marmi al rovere francese. &nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-5.jpg\" alt=\"40 Bleecker street new york\" class=\"wp-image-12353\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-5.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-5-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-5-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-5-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un\u2019eco moderna risuona negli iconici appartamenti ed esclusivi attici dagli altissimi soffitti, spazi dell\u2019abitare intrisi di bellezza atemporale che si svela attraverso un&#8217;autentica storia fatta di materiali e artigianalit\u00e0. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Protagonista indiscussa \u00e8 la luce naturale<\/strong>, che filtrando dalle razionali file di vetrate, &nbsp;dona luminosit\u00e0 agli ambienti e segue la linea morbida della facciata che, al pari della prua di una maestosa e placida nave, punta a nord-ovest. Un raro punto di osservazione su Noho e lo skyline del Village con i suoi grattacieli del dopoguerra. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4.jpg\" alt=\"40 Bleecker street new york\" class=\"wp-image-12355\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gli interni seguono un layout aperto che incoraggia la convivialit\u00e0 e la socialit\u00e0 domestica<\/strong>, pur nel rispetto della privacy; il soggiorno dialoga elegantemente con la cucina realizzata su misura da Ryan Korban, valorizzata dalla raffinatezza dei dettagli ed una certa preziosit\u00e0 dei materiali.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-14.jpg\" alt=\"\" data-id=\"12383\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-14.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12383\" class=\"wp-image-12383\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-14.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-14-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-14-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-14-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-22.jpg\" alt=\"\" data-id=\"12367\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-22.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12367\" class=\"wp-image-12367\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-22.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-22-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-22-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-21.jpg\" alt=\"\" data-id=\"12369\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-21.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12369\" class=\"wp-image-12369\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-21.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-21-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-21-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-20.jpg\" alt=\"\" data-id=\"12371\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-20.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12371\" class=\"wp-image-12371\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-20.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-20-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-20-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-20-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-19.jpg\" alt=\"\" data-id=\"12373\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-19.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12373\" class=\"wp-image-12373\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-19.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-19-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-19-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-18.jpg\" alt=\"\" data-id=\"12375\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-18.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12375\" class=\"wp-image-12375\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-18.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-18-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-18-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-18-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-15.jpg\" alt=\"\" data-id=\"12381\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-15.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12381\" class=\"wp-image-12381\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-15.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-15-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-15-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-15-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-17.jpg\" alt=\"\" data-id=\"12377\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-17.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12377\" class=\"wp-image-12377\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-17.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-17-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-17-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-17-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-16.jpg\" alt=\"\" data-id=\"12379\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-16.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12379\" class=\"wp-image-12379\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-16.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-16-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-16-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-16-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-13.jpg\" alt=\"\" data-id=\"12385\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-13.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12385\" class=\"wp-image-12385\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-13.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-13-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-13-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-13-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12.jpg\" alt=\"\" data-id=\"12387\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12387\" class=\"wp-image-12387\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11.jpg\" alt=\"\" data-id=\"12389\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12389\" class=\"wp-image-12389\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10.jpg\" alt=\"\" data-id=\"12391\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12391\" class=\"wp-image-12391\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019architetto ottiene una magica formula alchemica dosando sapientemente <strong>il calore dei pavimenti in rovere francese alla liscia freddezza del marmo<\/strong>. Una suggestiva isola levigata a mano si erge come un&#8217;opera d&#8217;arte scultorea affermandosi come punto focale dell\u2019intero spazio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\">Penthouse One-11: la sinuosa torre di comando Zaha Hadid a Citylife<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un lusso discreto \u00e8 rappresentato da alcuni arredi in rovere con inserti di vetro scanalato color bronzo e dettagli in nichel brunito<\/strong> -firmati SA Baxter &#8211; che creano uno splendido gioco di contrasti con alcuni elementi di derivazione \u201cbrutalista\u201d, come ad esempio la cappa in pietra. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-3.jpg\" alt=\"40 Bleecker street new york\" class=\"wp-image-12357\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-3.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-3-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-3-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-3-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Gli elettrodomestici Miele e gli accessori Lefroy Brooks danno forma alla funzionalit\u00e0 ed aggiungono un tocco sofisticato all\u2019insieme. <strong>La fresca camera da letto padronale<\/strong>, oasi di tranquilla serenit\u00e0 dalla tenue palette di colori, si affaccia sul viale alberato di Bleecker Street. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/tel-aviv-penthouse-irma-orenstein\/\">A Tel Aviv, una penthouse uranica si apre alla citt\u00e0<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anche qui<\/strong> il nexus del progetto, elemento di vera <strong>continuit\u00e0 spaziale, \u00e8 il sofisticato pavimento ligneo con geometria Chevron<\/strong> (o <strong>punto d\u2019Ungheria<\/strong> per ricordare le aristocratiche residenze storiche mitteleuropee); mentre le maestose finestre a tutta altezza invitano il libero fluire della luce e dilatano la percezione spaziale.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-9.jpg\" alt=\"\" data-id=\"12399\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-9.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12399\" class=\"wp-image-12399\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-9.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-9-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-9-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-9-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-1.jpg\" alt=\"\" data-id=\"12393\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12393\" class=\"wp-image-12393\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-1.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-1-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-1-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-12-1-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11-1.jpg\" alt=\"\" data-id=\"12395\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12395\" class=\"wp-image-12395\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11-1.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11-1-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-11-1-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10-1.jpg\" alt=\"\" data-id=\"12397\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12397\" class=\"wp-image-12397\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10-1.jpg 666w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10-1-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-10-1-333x500.jpg 333w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-8.jpg\" alt=\"\" data-id=\"12401\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-8.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12401\" class=\"wp-image-12401\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-8.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-8-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-8-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-8-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-7.jpg\" alt=\"\" data-id=\"12403\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-7.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12403\" class=\"wp-image-12403\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-7.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-7-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-7-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-7-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-6.jpg\" alt=\"\" data-id=\"12405\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-6.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12405\" class=\"wp-image-12405\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-6.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-6-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-6-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-6-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-1.jpg\" alt=\"\" data-id=\"12409\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12409\" class=\"wp-image-12409\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-1.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-1-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-1-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-4-1-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-2-1.jpg\" alt=\"\" data-id=\"12413\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-2-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=12413\" class=\"wp-image-12413\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-2-1.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-2-1-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-2-1-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-2-1-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Adiacente alla grande cabina armadio, il bagno padronale sale di livello per conformarsi alle nuove esigenze di benessere e wellness. <strong>La profondit\u00e0 della pietra levigata Grigio Colomba<\/strong> bilancia il rivestimento in rovere sbiancato della \u201cdoppia vanit\u00e0\u201d personalizzata da Korban, circondata da una composizione di specchio e vetro, che riflette luce e rimanda ad inediti scorci dello spazio circostante. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/villa-istanbul\/\">Una villa che rispecchia lo spirito della citt\u00e0 che la ospita, Istanbul<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Altre due camere da letto &#8211; &nbsp;sobriamente arredate nella singolare sinfonia di stile che Korban orchestra tra materiali, texture e toni espressivi- &nbsp;ospitano un bagno interno. <strong>Il progetto di &nbsp;illuminazione \u00e8 stato disegnato e curato da Bill Schwinghammer.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-1-1.jpg\" alt=\"40 Bleecker street new york\" class=\"wp-image-12421\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-1-1.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-1-1-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-1-1-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-1-1-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Non si poteva fare niente di pi\u00f9 per rendere unico ed inimitabile questo progetto abitativo&nbsp;ricco di memorie e testimone di un <strong>quartiere di new York, Noho<\/strong> per l\u2019appunto, che la famiglia Astor seppe trasformare nel XIX secolo in un\u2019esclusiva enclave per artisti et Beaux Arts.Un angolo spazzato da venti di creativit\u00e0 e nuove energie, che ci sfiorano ancora oggi, se solo ci soffermiamo a camminare lungo le sue vie acciottolate.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/villa-tyra-venetian-island-miami\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/woodflooring_slide_lago-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/villa-tyra-venetian-island-miami\/\" rel=\"bookmark\">Villa Tyra: una villa dal   twist contemporaneo affacciata sul golfo di Miami<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/audemars-piguet-barcellona\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/07\/audermars-piguet-barcellona-500x239.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/audemars-piguet-barcellona\/\" rel=\"bookmark\">AP House Barcelona, la casa di Audemars Piguet domina il tempo<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/star-22-una-residenza-di-lusso-sulla-isla-bonita\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/22star-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/star-22-una-residenza-di-lusso-sulla-isla-bonita\/\" rel=\"bookmark\">Star 22, una residenza di lusso sulla \u201cIsla Bonita\u201d<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/citylife_zaha_hadid_woodfloor-40-1-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\">Penthouse One-11: la sinuosa torre di comando Zaha Hadid a Citylife<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Svelato a NoHo&nbsp;40 Bleecker street; il nuovo progetto residenziale di lusso a New York riporta in vita un pezzo di [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":12345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-12341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Svelato a NoHo, 40 Bleecker street, il nuovo progetto residenziale di lusso a New York, a pochi passi da East Village.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese\" \/>\n<meta property=\"og:description\" content=\"Svelato a NoHo&nbsp;40 Bleecker street; il nuovo progetto residenziale di lusso a New York riporta in vita un pezzo di storia centenaria, a pochi passi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-15T11:36:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-05T11:16:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Debora Vella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Debora Vella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/\"},\"author\":{\"name\":\"Debora Vella\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/f51ca90669d11c0686d559f6d2a4a54d\"},\"headline\":\"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese\",\"datePublished\":\"2021-02-15T11:36:11+00:00\",\"dateModified\":\"2021-03-05T11:16:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/\"},\"wordCount\":749,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/40-Bleecker-street-new-york.jpg\",\"articleSection\":[\"Architettura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/\",\"name\":\"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/40-Bleecker-street-new-york.jpg\",\"datePublished\":\"2021-02-15T11:36:11+00:00\",\"dateModified\":\"2021-03-05T11:16:23+00:00\",\"description\":\"Svelato a NoHo, 40 Bleecker street, il nuovo progetto residenziale di lusso a New York, a pochi passi da East Village.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/40-Bleecker-street-new-york.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/40-Bleecker-street-new-york.jpg\",\"width\":1000,\"height\":805,\"caption\":\"40 Bleecker street\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/40-bleecker-street-new-york\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/f51ca90669d11c0686d559f6d2a4a54d\",\"name\":\"Debora Vella\",\"sameAs\":[\"http:\\\/\\\/www.listonegiordano.com\"],\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/debora\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese | One Listone Giordano","description":"Svelato a NoHo, 40 Bleecker street, il nuovo progetto residenziale di lusso a New York, a pochi passi da East Village.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/","og_locale":"it_IT","og_type":"article","og_title":"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese","og_description":"Svelato a NoHo&nbsp;40 Bleecker street; il nuovo progetto residenziale di lusso a New York riporta in vita un pezzo di storia centenaria, a pochi passi","og_url":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2021-02-15T11:36:11+00:00","article_modified_time":"2021-03-05T11:16:23+00:00","og_image":[{"width":1000,"height":805,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york.jpg","type":"image\/jpeg"}],"author":"Debora Vella","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Debora Vella","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/"},"author":{"name":"Debora Vella","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/f51ca90669d11c0686d559f6d2a4a54d"},"headline":"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese","datePublished":"2021-02-15T11:36:11+00:00","dateModified":"2021-03-05T11:16:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/"},"wordCount":749,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york.jpg","articleSection":["Architettura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/","url":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/","name":"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york.jpg","datePublished":"2021-02-15T11:36:11+00:00","dateModified":"2021-03-05T11:16:23+00:00","description":"Svelato a NoHo, 40 Bleecker street, il nuovo progetto residenziale di lusso a New York, a pochi passi da East Village.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york.jpg","width":1000,"height":805,"caption":"40 Bleecker street"},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/f51ca90669d11c0686d559f6d2a4a54d","name":"Debora Vella","sameAs":["http:\/\/www.listonegiordano.com"],"url":"https:\/\/www.listonegiordano.com\/one\/author\/debora\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/12341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=12341"}],"version-history":[{"count":16,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/12341\/revisions"}],"predecessor-version":[{"id":13031,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/12341\/revisions\/13031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/12345"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=12341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=12341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=12341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}