{"id":13613,"date":"2021-03-31T12:57:17","date_gmt":"2021-03-31T10:57:17","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=13613"},"modified":"2021-03-31T16:00:00","modified_gmt":"2021-03-31T14:00:00","slug":"cambiamenti-climatici-pefc-aumento-temperature","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/","title":{"rendered":"Cambiamento climatico: ce lo raccontano gli alberi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gli effetti negativi del <strong>cambiamento climatico<\/strong> si abbattono anche sugli alberi, compromettendone la dormienza invernale e anticipando il risveglio primaverile, riducendone crescita e produttivit\u00e0, facendo diventare le piante pi\u00f9 suscettibili a malattie e agli stress ambientali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli alberi, dunque, sono delle antenne dai ricettori sensibilissimi che captano variazioni dell\u2019ambiente circostante come, ad esempio, percentuale di umidit\u00e0, acqua, temperatura, stagione dell\u2019anno; tutti fattori che influiscono sulla stato di salute dell&#8217;intero eco-sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo conferma il<strong><em> Rapporto TRACE <\/em><\/strong>(Tree monitoring to support climate Adaptation and mitigation through PEFC Certification) redatto dal Segretario generale del <strong><a href=\"https:\/\/www.pefc.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">PEFC Italia<\/a><\/strong>, <strong>Antonio Brunori<\/strong>, basato su un <strong>monitoraggio durato quasi 800 giorni<\/strong> all\u2019interno della foresta umbra di Piegaro. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Condotto nell\u2019ambito del <strong>progetto scientifico<\/strong> <strong>TRACE<\/strong> e promosso dal <strong>Gruppo Margaritelli<\/strong> e da <strong>PEFC Italia<\/strong> con la collaborazione scientifica della <strong>Fondazione Centro Euro-Mediterraneo sui Cambiamenti Climatici <\/strong>(CMCC); questa iniziativa, unica in Italia, si unisce ad altre simili del CMCC in Cina, Russia e Spagna, ha permesso di conoscere lo stato di salute delle piante attraverso un\u2019attenta osservazione effettuata direttamente nella foresta. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Cambiamenti climatici: la foresta che racconta l&#039;evoluzione del clima \u00e8 in Umbria\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/l8rxXYbL0y0?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.listonegiordano.com\/one\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lo scopo di questo progetto nel bosco certificato per la Gestione Forestale Sostenibile, avvalorato dal doppio protocollo PEFC e FSC,  \u00e8 quello di avere gli strumenti adeguati per misurare la capacit\u00e0 di reazione dei boschi in tempi di emergenza climatica, di monitoraggio degli ecosistemi forestali e quindi per migliorare la qualit\u00e0 della gestione forestale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il bosco tra Citt\u00e0 della Pieve e Piegaro, di propriet\u00e0 della famiglia Margaritelli, ha ospitato negli anni numerose iniziative dedicate all\u2019innovazione, all\u2019ambiente e alla formazione sulla cultura del legno, diventando un vero e proprio &#8220;<strong><em>laboratorio a cielo aperto<\/em><\/strong>&#8221; (in questo caso per una sperimentazione tecnologica all\u2019avanguardia basata sull&#8217;Internet of things). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/natura\/danza-respiro-della-natura\/\">Danza: il respiro della Natura, armonia e unit\u00e0 fin dall\u2019antichit\u00e0<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>I primi dati sulla salute della foresta<\/strong> \u2013 presentati in occasione della giornata nazionale degli alberi &#8211; sono stati raccolti grazie ai \u201cTree-Talker\u201d, innovativi <strong>sensori installati direttamente sui tronchi, capaci di trasmettere ogni ora e via internet utilissime informazioni<\/strong> (incrociate con le condizioni meteorologiche locali) sulle <strong>quantit\u00e0 d\u2019acqua assorbita dalle piante, sulla qualit\u00e0 e sul colore del fogliame, informando quindi sullo stato di debolezza derivante dalla presenza di malattie all\u2019interno degli organismi vegetali.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/02\/9-1-1024x576.jpg\" alt=\"foresta dall'alto Piegaro Umbria\" class=\"wp-image-6122\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/02\/9-1-1024x576.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/02\/9-1-300x169.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/02\/9-1-768x432.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/02\/9-1-1536x864.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/02\/9-1-500x281.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/02\/9-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Foresta vista dall&#8217;alto | Piegaro Umbria<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dall\u2019ottobre del 2018 ad oggi, le osservazioni hanno permesso di accertare un anticipo nella ripresa vegetativa degli alberi che ha causato una germogliazione anticipata e un ritardo nella senescenza autunnale<\/strong>. Si tratta di una reazione direttamente collegata al cambiamento climatico, in particolare al riscaldamento globale, che ha gi\u00e0 aumentato la possibilit\u00e0 di caduta dei fiori, la relativa scarsa produzione nell\u2019anno e la maturazione dei frutti di numerosissime piante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Piegaro<\/strong>, nello specifico, <strong>la temperatura \u00e8 aumentata di ben 1.64 gradi rispetto a cinquanta anni fa e a causa degli inverni insolitamente caldi<\/strong>, gli alberi non riescono a incamerare quell\u2019indispensabile fabbisogno minimo di freddo che gli permette di risvegliarsi completamente dal letargo invernale. Tutto ci\u00f2 non incide soltanto sulla salute delle piante e sulla resistenza alle malattie ma anche sulla loro capacit\u00e0 produttiva.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Superquark: foreste hi tech, il progetto TRACE protagonista della puntata\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/jKm5kk7BBXU?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.listonegiordano.com\/one\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alcuni alberi, come il pino nero e la douglasia, hanno infatti prolungato la loro fase attiva fotosintetica invernale,<\/strong> mentre il cerro e il ciliegio, anch\u2019essi presenti nella foresta della famiglia Margaritelli, hanno presentato i sintomi di una crescita pi\u00f9 lenta (a causa della prolungata siccit\u00e0 estiva), e una perdita delle foglie molto ritardata rispetto alla norma. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le piante monitorate a Piegaro, nel complesso, hanno allungato la propria stagione vegetativa di circa 20 giorni<\/strong>. Una delle conseguenze pi\u00f9 drammatiche del riscaldamento globale, da questo punto di vista, sar\u00e0 il cambiamento nella distribuzione geografica delle piante, specialmente nel lungo periodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo monitoraggio vuole essere un ulteriore campanello d\u2019allarme, un messaggio rivolto a tutti, non solo alla comunit\u00e0 scientifica. Emerge infatti da un&#8217;analisi sull\u2019emergenza climatica delle citt\u00e0 europee, che <strong>la temperatura media nei comuni italiani \u00e8 cresciuta in media di 2,2\u00b0C nel giro di cinquant&#8217;anni<\/strong>, con un aumento che ha toccato picchi di oltre 4\u00b0C in alcune aree del paese (3,4\u00b0 a Milano, 3,6\u00b0 a Roma).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Continueremo ad ascoltare la voce degli &#8220;<strong>alberi parlanti&#8221;<\/strong>, l&#8217;unica che pu\u00f2 guidarci fuori da questa emergenza, che sembra assomigliare sempre pi\u00f9 ad una patologia cronicizzata. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grazie alla collaborazione con Antonio Brunori &#8211; Segretario Generale PEFC Italia<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/la-sostenibilita-culturale-fra-tradizione-e-design\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/sostenibilita\u0300-culturale_3-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/la-sostenibilita-culturale-fra-tradizione-e-design\/\" rel=\"bookmark\">La sostenibilit\u00e0 culturale fra tradizione e design<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/borgo-biologico-cairano\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/01\/borgo-biologico-cairano-3-500x313.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/\">Maurizio De Caro<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/borgo-biologico-cairano\/\" rel=\"bookmark\">Cairano Borgo Biologico: tutto il mondo in un paese<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/natura\/wood-therapy-foresta\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/07\/danza_aera_bosco_piegaro-38-500x375.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/natura\/wood-therapy-foresta\/\" rel=\"bookmark\">Wood Therapy: l&#8217;abbraccio della foresta<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/apfelhotel-un-progetto-nato-dalla-tentazione-originale-della-mela\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/09\/apfelhotel_noa-11-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/apfelhotel-un-progetto-nato-dalla-tentazione-originale-della-mela\/\" rel=\"bookmark\">Apfelhotel: un progetto nato dalla tentazione &#8220;originale&#8221; della mela.<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gli effetti negativi del cambiamento climatico si abbattono anche sugli alberi, compromettendone la dormienza invernale e anticipando il risveglio primaverile, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-13613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/oak_forest_france-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cambiamento climatico: ce lo raccontano gli alberi | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Gli effetti negativi del cambiamento climatico si abbattono sugli alberi, riducendone crescita e rendendoli pi\u00f9 suscettibili a malattie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambiamento climatico: ce lo raccontano gli alberi\" \/>\n<meta property=\"og:description\" content=\"Gli effetti negativi del cambiamento climatico si abbattono anche sugli alberi, compromettendone la dormienza invernale e anticipando il risveglio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-31T10:57:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-31T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/oak_forest_france.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/8a45898c971969498387c2725b55454e\"},\"headline\":\"Cambiamento climatico: ce lo raccontano gli alberi\",\"datePublished\":\"2021-03-31T10:57:17+00:00\",\"dateModified\":\"2021-03-31T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/\"},\"wordCount\":731,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/oak_forest_france.jpg\",\"articleSection\":[\"Natura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/\",\"name\":\"Cambiamento climatico: ce lo raccontano gli alberi | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/oak_forest_france.jpg\",\"datePublished\":\"2021-03-31T10:57:17+00:00\",\"dateModified\":\"2021-03-31T14:00:00+00:00\",\"description\":\"Gli effetti negativi del cambiamento climatico si abbattono sugli alberi, riducendone crescita e rendendoli pi\u00f9 suscettibili a malattie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/oak_forest_france.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/oak_forest_france.jpg\",\"width\":1200,\"height\":800,\"caption\":\"foresta Francia Selvicultura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/cambiamenti-climatici-pefc-aumento-temperature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cambiamento climatico: ce lo raccontano gli alberi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/8a45898c971969498387c2725b55454e\",\"name\":\"Redazione\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/r-listonegiordano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cambiamento climatico: ce lo raccontano gli alberi | One Listone Giordano","description":"Gli effetti negativi del cambiamento climatico si abbattono sugli alberi, riducendone crescita e rendendoli pi\u00f9 suscettibili a malattie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/","og_locale":"it_IT","og_type":"article","og_title":"Cambiamento climatico: ce lo raccontano gli alberi","og_description":"Gli effetti negativi del cambiamento climatico si abbattono anche sugli alberi, compromettendone la dormienza invernale e anticipando il risveglio","og_url":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2021-03-31T10:57:17+00:00","article_modified_time":"2021-03-31T14:00:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/oak_forest_france.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/"},"author":{"name":"Redazione","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/8a45898c971969498387c2725b55454e"},"headline":"Cambiamento climatico: ce lo raccontano gli alberi","datePublished":"2021-03-31T10:57:17+00:00","dateModified":"2021-03-31T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/"},"wordCount":731,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/oak_forest_france.jpg","articleSection":["Natura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/","url":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/","name":"Cambiamento climatico: ce lo raccontano gli alberi | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/oak_forest_france.jpg","datePublished":"2021-03-31T10:57:17+00:00","dateModified":"2021-03-31T14:00:00+00:00","description":"Gli effetti negativi del cambiamento climatico si abbattono sugli alberi, riducendone crescita e rendendoli pi\u00f9 suscettibili a malattie.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/oak_forest_france.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/oak_forest_france.jpg","width":1200,"height":800,"caption":"foresta Francia Selvicultura"},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/cambiamenti-climatici-pefc-aumento-temperature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Cambiamento climatico: ce lo raccontano gli alberi"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/8a45898c971969498387c2725b55454e","name":"Redazione","url":"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/13613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=13613"}],"version-history":[{"count":33,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/13613\/revisions"}],"predecessor-version":[{"id":13668,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/13613\/revisions\/13668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/7971"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=13613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=13613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=13613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}