{"id":15001,"date":"2021-08-27T15:50:57","date_gmt":"2021-08-27T13:50:57","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=15001"},"modified":"2021-08-27T15:50:58","modified_gmt":"2021-08-27T13:50:58","slug":"palazzo-della-luce-simbolo-di-eclettismo","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/","title":{"rendered":"Palazzo della luce, simbolo di eclettismo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>PETER JAEGER ARCHITETTI<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un\u2019architettura eclettica di inizio Novecento nel centro di Torino rivive con abitazioni di lusso, uffici e giardini pensili. Abitazioni di lusso e uffici, banche e servizi di ristorazione: il <strong>Palazzo della Luce<\/strong> a <strong>Torino<\/strong> rivive grazie al progetto di recupero e riconversione firmato da <strong>Peter Jaeger Architetti<\/strong>. Questa architettura eclettica di inizio Novecento, incorniciata dai giardini La Marmora, sorge nella parte pi\u00f9 antica della citt\u00e0. Progettato da <strong>Carlo Angelo Ceresa<\/strong>, il palazzo <strong>\u00e8 stato sede della Societ\u00e0 Idroelettrica Piemontese (SIP), poi di Enel<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-4.jpg\" alt=\"Palazzo della Luce - Torino\" class=\"wp-image-15013\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-4.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-4-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-4-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-4-500x334.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Palazzo della Luce &#8211; Torino<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le prime trasmissioni radiofoniche pubbliche italiane vennero irradiate proprio da questo edificio, che nel 1929 ospit\u00f2 l\u2019inaugurazione ufficiale di Radio Torino. In anni recenti, il marchio Living Supreme ha avviato un intervento di riqualificazione architettonica per una superficie complessiva di 21.000 m2. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/la-samaritaine-parigi\/\">La Samaritaine di Parigi risorge come l\u2019araba fenice grazie al progetto firmato SANAA<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I progettisti stabiliscono una chiara distinzione tra le parti originali e quelle contemporanee, realizzate con finiture in acciaio, vetro e legno, seguendo principi di efficienza energetica e sostenibilit\u00e0. <strong>Il palazzo presenta una facciata scenografica ispirata ai fasti della Belle \u00c9poque<\/strong>, coronata da due gruppi scultorei in travertino, opera di Edoardo Rubino. All\u2019interno, lo scalone monumentale in marmo conduce al piano nobile, dove si trova il <strong>salone neobarocco<\/strong>, con una volta a cassettoni decorata da rosoni in stucco.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-1.jpg\" alt=\"Palazzo della Luce - Torino\" class=\"wp-image-15017\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-1.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-1-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-1-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-1-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Palazzo della Luce &#8211; Torino<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il progetto dello studio torinese <a href=\"http:\/\/www.peterjaeger.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Peter Jaeger Architetti<\/a> mantiene e valorizza gli esterni in pietra e la struttura dell\u2019edificio<\/strong>, introducendo importanti trasformazioni all\u2019interno e moltiplicando lo spazio con l\u2019inserimento di soppalchi e collegamenti verticali. I progettisti stabiliscono una chiara distinzione tra le parti originali e quelle contemporanee, realizzate con <strong>finiture in acciaio, vetro e legno, seguendo principi di efficienza energetica e sostenibilit\u00e0. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-2.jpg\" alt=\"Palazzo della Luce - Torino\" class=\"wp-image-15015\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-2.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-2-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-2-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-2-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Palazzo della Luce &#8211; Torino<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le nuove destinazioni d\u2019uso comprendono uffici e servizi nei piani pi\u00f9 bassi e abitazioni di lusso ai livelli superiori. L\u2019edificio ospita gli uffici di Equitalia, organizzati attorno al grande salone semicircolare aperto al pubblico, con archivi e altri spazi nelle maniche laterali. Sono inoltre presenti otto unit\u00e0 di uffici di grande rappresentanza, sviluppati su pianta libera con arredi flessibili. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce.jpg\" alt=\"Palazzo della Luce - Torino\" class=\"wp-image-15019\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-768x511.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-500x333.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Palazzo della Luce &#8211; Torino<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La parte residenziale di Palazzo della Luce si articola in 12 abitazioni esclusive<\/strong>, ciascuna con una propria area esterna: loft con ampi patii al piano, appartamenti a sviluppo verticale con giardini pensili e ville urbane con spazi all\u2019aperto su pi\u00f9 livelli. Le residenze sono dotate di servizi extra come parcheggi interrati, palestra privata e portineria.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/torre-milano\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/06\/Torre-Milano--500x375.jpeg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/torre-milano\/\" rel=\"bookmark\">Torre Milano: l\u2019architettura alza lo sguardo<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/tel-aviv-penthouse-irma-orenstein\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/LEJA_PENTHOUSE_038-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/tel-aviv-penthouse-irma-orenstein\/\" rel=\"bookmark\">A Tel Aviv, una penthouse uranica si apre alla citt\u00e0<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/02\/40-Bleecker-street-new-york-500x403.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 5 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/40-bleecker-street-new-york\/\" rel=\"bookmark\">40 Bleecker street: il fascino ritrovato di una storica architettura newyorkese<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/design\/come-scegliere-il-pavimento-parquet\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-39-1-500x334.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/design\/come-scegliere-il-pavimento-parquet\/\" rel=\"bookmark\">Come scegliere il pavimento: il design di superficie<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>PETER JAEGER ARCHITETTI Un\u2019architettura eclettica di inizio Novecento nel centro di Torino rivive con abitazioni di lusso, uffici e giardini [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":15011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-15001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-3-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Palazzo della luce, simbolo di eclettismo | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Palazzo della Luce a Torino rivive grazie al progetto di recupero e riconversione firmato da Peter Jaeger Architetti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palazzo della luce, simbolo di eclettismo\" \/>\n<meta property=\"og:description\" content=\"PETER JAEGER ARCHITETTI Un\u2019architettura eclettica di inizio Novecento nel centro di Torino rivive con abitazioni di lusso, uffici e giardini pensili.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-27T13:50:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-27T13:50:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"The Plan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Plan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/\"},\"author\":{\"name\":\"The Plan\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/1e7b8d76999b4286a93b372b678f3410\"},\"headline\":\"Palazzo della luce, simbolo di eclettismo\",\"datePublished\":\"2021-08-27T13:50:57+00:00\",\"dateModified\":\"2021-08-27T13:50:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/palazzo-della-luce-3.jpg\",\"articleSection\":[\"Architettura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/\",\"name\":\"Palazzo della luce, simbolo di eclettismo | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/palazzo-della-luce-3.jpg\",\"datePublished\":\"2021-08-27T13:50:57+00:00\",\"dateModified\":\"2021-08-27T13:50:58+00:00\",\"description\":\"Palazzo della Luce a Torino rivive grazie al progetto di recupero e riconversione firmato da Peter Jaeger Architetti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/palazzo-della-luce-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/palazzo-della-luce-3.jpg\",\"width\":1000,\"height\":750,\"caption\":\"Palazzo della Luce - Torino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-della-luce-simbolo-di-eclettismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palazzo della luce, simbolo di eclettismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/1e7b8d76999b4286a93b372b678f3410\",\"name\":\"The Plan\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/t-plan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Palazzo della luce, simbolo di eclettismo | One Listone Giordano","description":"Palazzo della Luce a Torino rivive grazie al progetto di recupero e riconversione firmato da Peter Jaeger Architetti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/","og_locale":"it_IT","og_type":"article","og_title":"Palazzo della luce, simbolo di eclettismo","og_description":"PETER JAEGER ARCHITETTI Un\u2019architettura eclettica di inizio Novecento nel centro di Torino rivive con abitazioni di lusso, uffici e giardini pensili.","og_url":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2021-08-27T13:50:57+00:00","article_modified_time":"2021-08-27T13:50:58+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-3.jpg","type":"image\/jpeg"}],"author":"The Plan","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"The Plan","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/"},"author":{"name":"The Plan","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/1e7b8d76999b4286a93b372b678f3410"},"headline":"Palazzo della luce, simbolo di eclettismo","datePublished":"2021-08-27T13:50:57+00:00","dateModified":"2021-08-27T13:50:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/"},"wordCount":429,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-3.jpg","articleSection":["Architettura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/","url":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/","name":"Palazzo della luce, simbolo di eclettismo | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-3.jpg","datePublished":"2021-08-27T13:50:57+00:00","dateModified":"2021-08-27T13:50:58+00:00","description":"Palazzo della Luce a Torino rivive grazie al progetto di recupero e riconversione firmato da Peter Jaeger Architetti.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-3.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/08\/palazzo-della-luce-3.jpg","width":1000,"height":750,"caption":"Palazzo della Luce - Torino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-della-luce-simbolo-di-eclettismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Palazzo della luce, simbolo di eclettismo"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/1e7b8d76999b4286a93b372b678f3410","name":"The Plan","url":"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/15001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=15001"}],"version-history":[{"count":9,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/15001\/revisions"}],"predecessor-version":[{"id":15103,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/15001\/revisions\/15103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/15011"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=15001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=15001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=15001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}