{"id":16342,"date":"2022-02-22T09:35:31","date_gmt":"2022-02-22T08:35:31","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=16342"},"modified":"2022-02-22T09:38:58","modified_gmt":"2022-02-22T08:38:58","slug":"botanica-architettura-naturale","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/","title":{"rendered":"Botanica (o dell\u2019origine naturale dell\u2019architettura)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">0.1 (a Stefano Mancuso e Deproducer)<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Non al Cristianesimo, non all&#8217;entusiasmo religioso, ma solo all&#8217;entusiasmo della ragione dobbiamo l&#8217;esistenza di una botanica, di una mineralogia, di una zoologia, di una fisica e di una astronomia.\u201c <\/p><cite><meta charset=\"utf-8\"><p>Ludwig Feuerbach<\/p><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Mi piace l\u2019origine etimologica, ambigua, complessa, polimorfa, dal greco <em>botane<\/em>, pianta, elemento centrale del mondo e compressione semantica dell\u2019architettura: tutto \u00e8 pianta nelle discipline che studiamo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ora questa meraviglia, questo libro della natura dove possiamo leggere ogni forma di passato ma anche ogni potenzialit\u00e0 di futuro, sta diventando letteratura pericolosa, quasi un thriller, dove l<strong>a cultura del progetto dovr\u00e0 aiutare, curare l\u2019irreversibile crisi del pianeta che ha trasformato spesso senza alcuna tenerezza estetica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/botanica-stefano-mancuso\/\">Botanica, uno spettacolo di scienza in musica con Stefano Mancuso<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Botanica \u00e8 l\u2019opera totale dove natura e cultura si fondono verso un nuovo obiettivo antropologico, verso nuove ideologie antropomorfe, \u00e8 il mondo come avremmo voluto vedere, \u00e8 un cosmo che stava per sfuggirci di mano, senza un Dio buono in grado di controllare figli tanto degeneri.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-1024x1024.jpeg\" alt=\"green table botanica mancuso\" class=\"wp-image-15174\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-1024x1024.jpeg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-300x300.jpeg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-150x150.jpeg 150w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-768x768.jpeg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-1536x1536.jpeg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-500x500.jpeg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica.jpeg 1560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cosa possiamo fare ora, noi piccoli animaletti senzienti, di fronte allo scioglimento dei ghiacci perenni, al mare universale della plastica assassina, al biossido di carbonio che consuma lentamente la nostra anima e i nostri polmoni, che spegne il sole del nostro futuro e di quello dei nostri figli, cosa?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cambiare. \u00e8 possibile.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;L&#8217;agricoltura biologica ha un approccio sistemico, utilizzando le conoscenze di botanici patologi e genetisti, entomologi, microbiologi, allevatori e altri, per riorganizzare la terra in mini-ecosistemi, costituiti da reti di relazioni simbiotiche che interagiscono creando una comunit\u00e0 totale. La scienza dell&#8217;agricoltura biologica mette in discussione tutto ci\u00f2 che l&#8217;Illuminismo ha definito come modo di funzionamento della scienza: abbiamo sempre pensato alla scienza come a uno strumento per sfruttare le ricchezze della natura; oggi, una nuova generazione di scienziati ha in mente qualcosa di completamente diverso, cio\u00e8 usare la scienza per ristabilire rapporti ambientali e costruire comunit\u00e0 naturali.\u201c  <\/p><cite><meta charset=\"utf-8\"><p>Jeremy Rifkin<\/p><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Certo sembra facile, non consumare, o meglio consumare meno e meglio, invertire la tendenza della nostra pervicace comodit\u00e0, non sar\u00e0 facile perch\u00e9 inquinare, distruggere \u00e8 pi\u00f9 facile che preservare, conservare, aver cura del Creato se siete credenti o della Natura se siete laici sensibili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gli scienziati dovranno diventare gli alleati principali dei progettisti<\/strong>, le loro materie, le ricerche e le sperimentazioni saranno il nuovo testo kantiano del futuro prossimo architettonico, dove la disciplina originaria diventer\u00e0 altro rispetto alle nostre antiche certezze (come Wittgenstein insegnava molto prima di tutti).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/perche-larchitettura-ha-ancora-bisogno-della-filosofia\/\">Perch\u00e9 l\u2019architettura ha ancora bisogno della filosofia<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019estetica classica e moderna, contemporanea e post-moderna dovr\u00e0 nutrirsi d\u2019altro, come in una forma di nuovo spirito etico, morale verso un nuovo umanesimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In effetti lo studio delle piante e delle loro caratteristiche biologiche potr\u00e0 aiutarci a rendere la progettazione compiutamente ambientale<\/strong>, verso una tecnica gentile, entrando nel nuovo paradigma delle interdisciplinariet\u00e0 eco-sostenibile, visto come stimolo culturale e non come limite: un punto di arrivo che rappresenti la vera forza dell\u2019innovazione.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/11\/IMG_1153.jpg\" alt=\"Botanica Stefano Mancuso\" class=\"wp-image-15292\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/11\/IMG_1153.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/11\/IMG_1153-300x300.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/11\/IMG_1153-150x150.jpg 150w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/11\/IMG_1153-768x768.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/11\/IMG_1153-500x500.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Botanica &#8211; Stefano Mancuso  &#8211; Deproducers<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">I progettisti del futuro ma, anche del presente, dovranno essere pi\u00f9 scienziati e meno stilisti glamour, naturalisti e meno estetologi compulsivi, insomma <strong>la bellezza \u00e8 nelle forme della natura che diventa un metodo culturale<\/strong>, imitativo del mondo, come se l\u2019architettura fosse sempre esistita, anzi dovrebbe diventare, ambire ad essere invisibile, coerente con lo spazio ambientale che la contiene.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Probabilmente il significato stesso della prassi disciplinare cambier\u00e0, dovr\u00e0 diventare altro da s\u00e9, guardare con pi\u00f9 attenzione ai danni che lo sviluppo stesso del costruire ha determinato, in relazione ad una carenza di sensibilit\u00e0 del gesto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nello spazio e nel tempo, nel luogo e nella previsione di una caratterizzazione <em>dell\u2019adesso<\/em> come significato preconizzante <em>del dopo<\/em>, dell\u2019inconoscibile <em>oltre<\/em>, come se fosse una branchia della \u201cbotanica\u201d, come se ambisse a divenire l\u2019elemento di fusione tra la scienza, la tecnica e l\u2019estetica umana, la forma pi\u00f9 densa di antropologia culturale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/eredita-green-table\/\">L\u2019eredit\u00e0 di Green Table, da Perugia al Mondo<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La rivoluzione concettuale in corso non da tregua ai passatisti teorici, sviluppa modalit\u00e0 creative multiple, anzi multi-funzionali, come la costruzione di una nuova prassi filosofica, come una condizione nuova che non riusciamo a tenere alla distanza delle nostre retoriche residuali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nella botanica, l\u2019architettura si ricompone con la sua origine naturale<\/strong>, con la sua essenza ambientale, nella sua dialettica con mondo, \u00e8 passato molto tempo e non ci siamo accorti che la natura artificiale del progetto poteva portarci nell\u2019abisso insensibile della marginalit\u00e0 esistenziale, non pi\u00f9 opere ma azioni servono per dirci compiutamente realizzati sia come uomini che come architetti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/architettura-naturale-franciacorta\/\">Un\u2019architettura naturale in Franciacorta: ti ricordi quella casa nel bosco?<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il tempo \u00e8 passato come un sospiro, la Madre Terra ha sopportato, corretto, avvertito di tutti i pericoli, reali o apparenti, ora il senso di responsabilit\u00e0 bussa alla porta degli esseri umani che vogliono ancora abitare in questa meraviglia che ci hanno regalato, senza l\u2019incubo dell\u2019ennesima apocalisse, senza l\u2019ansia di una possibile e prematura estinzione.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c\u00c8 insensato continuare a confidare nel mito di una crescita illimitata, misurata in base a quel dio-feticcio che \u00e8 il prodotto nazionale lordo: una crescita che oltretutto provoca (in termini di rifiuti, desertificazione, inquinamento, consumo del territorio eccetera) ingenti costi sociali&#8230;\u201d<\/p><cite><meta charset=\"utf-8\"><p>Antonio Cederna<\/p><\/cite><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/residenza-bologna-parquet-rovere\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/parquet-rovere-spina-ungherese-500x344.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 4 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/residenza-bologna-parquet-rovere\/\" rel=\"bookmark\">Una residenza di famiglia con vista sui tetti bolognesi<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/eredita-green-table\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Botanica-500x500.jpeg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/\">Maurizio De Caro<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 4 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/eredita-green-table\/\" rel=\"bookmark\">L\u2019eredit\u00e0 di Green Table, da Perugia al Mondo<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/botanica-stefano-mancuso\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/11\/IMG_1153-500x500.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 4 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/botanica-stefano-mancuso\/\" rel=\"bookmark\">Botanica, uno spettacolo di scienza in musica con Stefano Mancuso<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/green-table-2021\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2021\/10\/Green-Table-Andrea-Margaritelli-e-pubblico-500x333.jpeg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 4 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/green-table-2021\/\" rel=\"bookmark\">Green Table 2021, l&#8217;architettura del pensiero critico unisce terra e cielo<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>0.1 (a Stefano Mancuso e Deproducer) &#8220;Non al Cristianesimo, non all&#8217;entusiasmo religioso, ma solo all&#8217;entusiasmo della ragione dobbiamo l&#8217;esistenza di [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":16351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-16342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/architettura-naturale-150x150.webp","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Botanica (o dell\u2019origine naturale dell\u2019architettura) | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Lo studio delle piante e delle loro caratteristiche biologiche potr\u00e0 aiutarci a rendere la progettazione architettonica pi\u00f9 ambientale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Botanica (o dell\u2019origine naturale dell\u2019architettura)\" \/>\n<meta property=\"og:description\" content=\"Lo studio delle piante e delle loro caratteristiche biologiche potr\u00e0 aiutarci a rendere la progettazione architettonica pi\u00f9 ambientale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-22T08:35:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-22T08:38:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/architettura-naturale.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Maurizio De Caro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"0.1 (a Stefano Mancuso e Deproducer) &quot;Non al Cristianesimo, non all&#039;entusiasmo religioso, ma solo all&#039;entusiasmo della ragione dobbiamo l&#039;esistenza di una\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maurizio De Caro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/\"},\"author\":{\"name\":\"Maurizio De Caro\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\"},\"headline\":\"Botanica (o dell\u2019origine naturale dell\u2019architettura)\",\"datePublished\":\"2022-02-22T08:35:31+00:00\",\"dateModified\":\"2022-02-22T08:38:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/\"},\"wordCount\":880,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/architettura-naturale.webp\",\"articleSection\":[\"Natura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/\",\"name\":\"Botanica (o dell\u2019origine naturale dell\u2019architettura) | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/architettura-naturale.webp\",\"datePublished\":\"2022-02-22T08:35:31+00:00\",\"dateModified\":\"2022-02-22T08:38:58+00:00\",\"description\":\"Lo studio delle piante e delle loro caratteristiche biologiche potr\u00e0 aiutarci a rendere la progettazione architettonica pi\u00f9 ambientale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/architettura-naturale.webp\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/architettura-naturale.webp\",\"width\":1500,\"height\":1200,\"caption\":\"architettura natura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/natura\\\/botanica-architettura-naturale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botanica (o dell\u2019origine naturale dell\u2019architettura)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\",\"name\":\"Maurizio De Caro\",\"description\":\"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\\\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/decaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Botanica (o dell\u2019origine naturale dell\u2019architettura) | One Listone Giordano","description":"Lo studio delle piante e delle loro caratteristiche biologiche potr\u00e0 aiutarci a rendere la progettazione architettonica pi\u00f9 ambientale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/","og_locale":"it_IT","og_type":"article","og_title":"Botanica (o dell\u2019origine naturale dell\u2019architettura)","og_description":"Lo studio delle piante e delle loro caratteristiche biologiche potr\u00e0 aiutarci a rendere la progettazione architettonica pi\u00f9 ambientale.","og_url":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2022-02-22T08:35:31+00:00","article_modified_time":"2022-02-22T08:38:58+00:00","og_image":[{"width":1500,"height":1200,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/architettura-naturale.webp","type":"image\/webp"}],"author":"Maurizio De Caro","twitter_card":"summary_large_image","twitter_description":"0.1 (a Stefano Mancuso e Deproducer) \"Non al Cristianesimo, non all'entusiasmo religioso, ma solo all'entusiasmo della ragione dobbiamo l'esistenza di una","twitter_misc":{"Scritto da":"Maurizio De Caro","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/"},"author":{"name":"Maurizio De Caro","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481"},"headline":"Botanica (o dell\u2019origine naturale dell\u2019architettura)","datePublished":"2022-02-22T08:35:31+00:00","dateModified":"2022-02-22T08:38:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/"},"wordCount":880,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/architettura-naturale.webp","articleSection":["Natura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/","url":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/","name":"Botanica (o dell\u2019origine naturale dell\u2019architettura) | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/architettura-naturale.webp","datePublished":"2022-02-22T08:35:31+00:00","dateModified":"2022-02-22T08:38:58+00:00","description":"Lo studio delle piante e delle loro caratteristiche biologiche potr\u00e0 aiutarci a rendere la progettazione architettonica pi\u00f9 ambientale.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/architettura-naturale.webp","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2022\/02\/architettura-naturale.webp","width":1500,"height":1200,"caption":"architettura natura"},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/natura\/botanica-architettura-naturale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Botanica (o dell\u2019origine naturale dell\u2019architettura)"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481","name":"Maurizio De Caro","description":"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net","url":"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/16342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=16342"}],"version-history":[{"count":7,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/16342\/revisions"}],"predecessor-version":[{"id":16356,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/16342\/revisions\/16356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/16351"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=16342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=16342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=16342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}