{"id":25227,"date":"2024-06-14T08:00:00","date_gmt":"2024-06-14T06:00:00","guid":{"rendered":"https:\/\/www.listonegiordano.com\/one\/?p=25227"},"modified":"2024-06-10T16:04:05","modified_gmt":"2024-06-10T14:04:05","slug":"luce-su-misura","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/","title":{"rendered":"Spazi di luce: innovazione e design su misura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ogni prodotto di design ha sempre avuto l\u2019ambizione di essere unico, di trovare quello spazio che rende irripetibile ogni gesto della creazione, ogni momento della creativit\u00e0, dunque essere \u201csu misura\u201d significa andare a creare le condizioni per risolvere un problema di unicit\u00e0 nell\u2019essenza del percorso progettuale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In questo meraviglioso universo delle idee, la luce, \u201cla lampada\u201d moltiplica esponenzialmente questa necessit\u00e0 perch\u00e9 l\u2019immaterialit\u00e0 che proietta, che lancia nello spazio, rappresenta quella condizione essenziale che tende a differenziarsi da ogni altro esempio, come se la qualit\u00e0 del \u201csu misura\u201d fosse irrinunciabile.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano-682x1024.jpeg\" alt=\"Palazzo Reale, Milano. Piermarini Lighting Project\" class=\"wp-image-25238\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano-682x1024.jpeg 682w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano-200x300.jpeg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano-768x1152.jpeg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano-333x500.jpeg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.jpeg 933w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Quindi la tecnica e le tecnologia costruiscono per ogni prodotto, quello spazio culturale e progettuale che ogni produttore \u201cilluminato\u201d desidera , come se non esistessero alternative, e Panzeri esprime questa antica ma contemporanea volont\u00e0 , come in un processo continuo di trasformazione e di miglioramento, negli anni, come se ogni lampada fosse \u201cl\u2019ultima lampada del mondo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Think(and made) in Italy<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Forse il pensiero si caratterizza per una dislocazione geografica e fisica perch\u00e9 gli oggetti pensati in un luogo specifico hanno una caratterizzazione che li rende riconoscibili e non si pu\u00f2 negare questo processo di identificazione che parte dal <em>think in Italy<\/em> , per arrivare al <em>made in Italy.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Talmente significativo da aver raggiunto la dimensione di uno stile, di un principio ordinatore, di una sequenza di una sequenza di gesti che conducono l\u2019idea ad una particolare realizzazione, in un percorso consolidato nel tempo e nella storia che costruiscono da sempre la nostra \u201cIdentit\u00e0 Italiana\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Probabilmente tutto questo nasce&nbsp; dalla stratificazione delle nostre antiche conoscenze manuali, artigianali, artistiche e industriali che rendono particolare ogni prodotto, ma nel design della luce questo percorso \u00e8 ancora pi\u00f9 evidente perch\u00e9 la <em>\u201cLampada Panzeri\u201d<\/em> ha una densit\u00e0 di gesti e di segni che la rendono direttamente connessa col pensiero \u201dalto\u201d che l\u2019ha generata<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Un pensiero inimitabile, logico, denso di conoscenze etiche, estetiche e produttive, una sintesi concettuale che non ammette imitazioni, trasparente come solo la luce \u00e8 in grado di essere.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"637\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-1024x637.jpeg\" alt=\"Palazzo Reale, Milano. Piermarini Lighting Project\" class=\"wp-image-25234\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-1024x637.jpeg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-300x187.jpeg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-768x478.jpeg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-1536x955.jpeg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-2048x1274.jpeg 2048w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-500x311.jpeg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Tradizione nell\u2019 innovazione<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il passato \u00e8 la matrice di ogni gesto creativo contemporaneo, ne configura la capacit\u00e0 di produrre momenti innovativi, come in una linea continua che unisce quello ha costruito il nostro paesaggio degli oggetti, prima di diventare testimonianza del futuro del progetto di design.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-yoast-seo-related-links\"><li><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\">Penthouse One-11: la sinuosa torre di comando Zaha Hadid a Citylife<\/a><\/li><li><a href=\"https:\/\/www.listonegiordano.com\/one\/design\/ascolto-il-tuo-cuore-natura\/\">Ascolto il tuo cuore, natura.<\/a><\/li><li><a href=\"https:\/\/www.listonegiordano.com\/one\/design\/marianne-brandt-bauhaus\/\">Marianne Brandt, la dea del metallo al Bauhaus \u00a0<\/a><\/li><li><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/architettura-industriale\/\">Architettura Industriale: in Umbria l\u2019industria protegge la natura<\/a><\/li><li><a href=\"https:\/\/www.listonegiordano.com\/one\/natura\/la-cultura-del-legno\/\">La cultura del legno<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dunque \u00e8 un flusso incostante che miscela esperienze diverse e momenti storici che hanno plasmato il percorso millenario della creativit\u00e0, Panzeri ha un\u2019esperienza significativa all\u2019interno di questa dialettica tra \u201cantico\u201d e \u201cimmaginifico\u201d, come in una sequenza di episodi, di capitoli di un racconto sempre in trasformazione, perennemente in divenire. La storia della bellezza \u00e8 costellata di tanti momenti di svolta e quella della cultura del progetto \u00e8 un\u2019infinita sequenza di svolte che hanno incatenato indissolubilmente l\u2019innovazione alla tradizione, anche quando avevano la necessit\u00e0 di negare questo legame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non \u00e8 un tornare al passato, ma interpretarne le caratteristiche che &nbsp;ci hanno portato a fare le scelte di oggi, a costruire i meccanismi che rendono le nostre lampade, i nostri progetti frutto di un\u2019attenta lettura di quello che siamo stati come uomini, come progettisti e come imprenditori<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Filiera &nbsp;produttiva &nbsp;\u201cetica e sostenibile\u201d<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non \u00e8 una novit\u00e0 il chiedersi oltre a cosa produrre: come produrre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La dissoluzione della centralit\u00e0 dell\u2019estetica spinge prepotentemente l\u2019imprenditore a scelte nuove, ad un\u2019attenzione per la conoscenza delle nuove opportunit\u00e0 che la tecnologia \u201cdolce\u201d riesce a indicarci, senza dover rinunciare alla qualit\u00e0 finale del prodotto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il concetto di filiera produttiva \u201detica\u201d presuppone una crescita della sensibilit\u00e0 complessive che un\u2019azienda come Panzeri ha sempre tenuto in grande considerazione, soprattutto in un campo come quello del <em>\u201clighting design\u201d<\/em> dove la componete tecnologica ci appare continuamente in evoluzione, sia per il controllo energetico che per la qualit\u00e0 delle materie e delle componentistiche impiegate.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/PiermariniLighting-Project3_phPieroSimonetto-682x1024.jpg\" alt=\"Palazzo Reale, Milano. Piermarini Lighting Project\" class=\"wp-image-25232\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/PiermariniLighting-Project3_phPieroSimonetto-682x1024.jpg 682w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/PiermariniLighting-Project3_phPieroSimonetto-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/PiermariniLighting-Project3_phPieroSimonetto-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/PiermariniLighting-Project3_phPieroSimonetto-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/PiermariniLighting-Project3_phPieroSimonetto.jpg 933w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Non \u00e8 solo una necessit\u00e0 ambientale, per la salvaguardia e la cura del nostro pianeta, ma \u00e8 il tema della <em>\u201cresponsabilit\u00e0 civile\u201d<\/em> che ogni imprenditore deve tenere nella massima considerazione perch\u00e9 non abbiamo pi\u00f9 tempo per sprecare energia, per sprecare la luce , e il ben-essere che questo processo costruttivo determina non \u00e8 negoziabile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Cultura e Culture<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La luce ha sempre cercato di illuminare ogni gesto creativo, dall\u2019arte ai monumenti, il principio generatore di ogni progetto presuppone una presenza significativa e produttiva di ogni azienda che ha a cuore il patrimonio italiano, spesso soggetto a scarsa attenzione e manutenzione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Panzeri ha voluto dare un contributo materiale e concettuale intraprendendo una serie di iniziative rivolte alla risoluzione di problemi che gli spazi museali portano con se, modificando antichi percorsi culturali e razionalizzando con i propri prodotti,&nbsp; ambienti espositivi in varie parti del paese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Illuminazione dello scalone monumentale di Palazzo Reale, Milano. Piermarini Lighting Project<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/parquet-per-appartamento-in-montagna\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/06_STORAGE_KIRCHBERG_01-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 2 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/parquet-per-appartamento-in-montagna\/\" rel=\"bookmark\">Eleganza e contemporaneit\u00e0 per due progetti residenziali sulle Alpi austriache<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/natura\/ponte-vivente-di-alberi\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/ponte-vivente-fatto-da-radici-di-albero-in-india-500x334.jpeg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 2 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/natura\/ponte-vivente-di-alberi\/\" rel=\"bookmark\">Un ponte vivente nel cuore dell&#8217;India<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/studio-legale-a-bari\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/DSC5504-500x324.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 2 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/studio-legale-a-bari\/\" rel=\"bookmark\">La metamorfosi architettonica di uno studio legale a Bari<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/chateau-dans-le-maconnais\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/05\/Woo-Are-Yoo-19393-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 2 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/chateau-dans-le-maconnais\/\" rel=\"bookmark\">Ch\u00e2teau dans le M\u00e2connais: un viaggio nel XIV secolo<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ogni prodotto di design ha sempre avuto l\u2019ambizione di essere unico, di trovare quello spazio che rende irripetibile ogni gesto [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":25234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-25227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project-150x150.jpeg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spazi di luce: innovazione e design su misura | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Ogni prodotto di design come la luce ha sempre avuto l\u2019ambizione di essere unico, irripetibile su misura. Proprio come Panzeri design.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spazi di luce: innovazione e design su misura\" \/>\n<meta property=\"og:description\" content=\"Ogni prodotto di design ha sempre avuto l\u2019ambizione di essere unico, di trovare quello spazio che rende irripetibile ogni gesto della creazione, ogni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-14T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maurizio De Caro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maurizio De Caro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/\"},\"author\":{\"name\":\"Maurizio De Caro\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\"},\"headline\":\"Spazi di luce: innovazione e design su misura\",\"datePublished\":\"2024-06-14T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/\"},\"wordCount\":821,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg\",\"articleSection\":[\"Architettura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/\",\"name\":\"Spazi di luce: innovazione e design su misura | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg\",\"datePublished\":\"2024-06-14T06:00:00+00:00\",\"description\":\"Ogni prodotto di design come la luce ha sempre avuto l\u2019ambizione di essere unico, irripetibile su misura. Proprio come Panzeri design.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg\",\"width\":2560,\"height\":1592,\"caption\":\"Palazzo Reale, Milano. Piermarini Lighting Project\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/luce-su-misura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spazi di luce: innovazione e design su misura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\",\"name\":\"Maurizio De Caro\",\"description\":\"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\\\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/decaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spazi di luce: innovazione e design su misura | One Listone Giordano","description":"Ogni prodotto di design come la luce ha sempre avuto l\u2019ambizione di essere unico, irripetibile su misura. Proprio come Panzeri design.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/","og_locale":"it_IT","og_type":"article","og_title":"Spazi di luce: innovazione e design su misura","og_description":"Ogni prodotto di design ha sempre avuto l\u2019ambizione di essere unico, di trovare quello spazio che rende irripetibile ogni gesto della creazione, ogni","og_url":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2024-06-14T06:00:00+00:00","og_image":[{"width":2560,"height":1592,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg","type":"image\/jpeg"}],"author":"Maurizio De Caro","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maurizio De Caro","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/"},"author":{"name":"Maurizio De Caro","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481"},"headline":"Spazi di luce: innovazione e design su misura","datePublished":"2024-06-14T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/"},"wordCount":821,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg","articleSection":["Architettura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/","url":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/","name":"Spazi di luce: innovazione e design su misura | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg","datePublished":"2024-06-14T06:00:00+00:00","description":"Ogni prodotto di design come la luce ha sempre avuto l\u2019ambizione di essere unico, irripetibile su misura. Proprio come Panzeri design.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2024\/06\/Palazzo-Reale-Milano.-Piermarini-Lighting-Project.jpeg","width":2560,"height":1592,"caption":"Palazzo Reale, Milano. Piermarini Lighting Project"},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/luce-su-misura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Spazi di luce: innovazione e design su misura"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481","name":"Maurizio De Caro","description":"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net","url":"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/25227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=25227"}],"version-history":[{"count":2,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/25227\/revisions"}],"predecessor-version":[{"id":25240,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/25227\/revisions\/25240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/25234"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=25227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=25227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=25227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}