{"id":2604,"date":"2019-06-14T11:47:55","date_gmt":"2019-06-14T09:47:55","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=2604"},"modified":"2020-01-17T11:29:08","modified_gmt":"2020-01-17T10:29:08","slug":"graffi-massimo-iosa-ghini","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/","title":{"rendered":"Graffi | Massimo Iosa Ghini"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">I listelli, incisi e graffiati, sono sostenuti dalla luce, che come linfa li nutre. Il piano calpestabile acquista cos\u00ec una nuova dimensione, non pi\u00f9 passiva ma teatrale. <\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-2-1024x768.jpg\" alt=\"\" class=\"wp-image-4804\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-2-1024x768.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-2-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-2-768x576.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-2-1536x1152.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-2-500x375.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-2.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"666\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-10-1024x666.jpg\" alt=\"\" class=\"wp-image-4820\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-10-1024x666.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-10-300x195.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-10-768x500.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-10-1536x999.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-10-500x325.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-10.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFrutto della tradizione italiana e della raffinata ricerca di una grande azienda, questo <a href=\"https:\/\/www.listonegiordano.com\/one\/natura\/la-cultura-del-legno\/\">parquet<\/a> \u00e8 il risultato di un nobile accordo tra design, tecnologia ed innovazione. La luce, come linfa irradiante, invade la materia donandole nuova vita. Le superfici sono cos\u00ec ridisegnate sottolineando la tattilit\u00e0 del legno  nella sua forma pi\u00f9 pura\u201d. Legno e luce. Tecnologia e design. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queste le parole chiave di <strong>un parquet dalle caratteristiche decisamente innovative<\/strong>. Un prodotto che nasce dal singolare incontro tra un materiale di antica tradizione come il<a href=\"https:\/\/www.listonegiordano.com\/one\/design\/la-fabbrica-degli-alberi\/\"> legno<\/a> e soluzioni illuminotecniche di assoluta avanguardia. La speciale tecnologia led su basso spessore permette  di infondere \u201clinfa luminosa\u201d alla superficie secondo l\u2019idea ispiratrice e l\u2019originale interpretazione estetica del progettista. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-4-1024x768.jpg\" alt=\"\" class=\"wp-image-4801\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-4-1024x768.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-4-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-4-768x576.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-4-1536x1152.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-4-500x375.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-4.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"853\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/graffi_woodflooring_massimo_iosa_ghini-9-1024x853.jpg\" alt=\"\" class=\"wp-image-4109\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/graffi_woodflooring_massimo_iosa_ghini-9-1024x853.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/graffi_woodflooring_massimo_iosa_ghini-9-300x250.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/graffi_woodflooring_massimo_iosa_ghini-9-768x640.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/graffi_woodflooring_massimo_iosa_ghini-9-500x417.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/graffi_woodflooring_massimo_iosa_ghini-9.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dal punto di vista costruttivo il pavimento si caratterizza per l\u2019accoppiamento del legno a vista su uno speciale supporto inferiore in profilato di alluminio che, grazie a una serie di accorgimenti tecnici sull\u2019utilizzo e lavorazione dei materiali, controllo degli angoli di rifrazione della luce e dissipazione del calore, riesce a realizzare in soli pochi millimetri di spessore un completo ed efficiente sistema di retroilluminazione a led. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"651\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-7-1024x651.jpg\" alt=\"\" class=\"wp-image-4806\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-7-1024x651.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-7-300x191.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-7-768x488.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-7-1536x977.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-7-500x318.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-7.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"853\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1024x853.jpg\" alt=\"\" data-id=\"4809\" data-link=\"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/attachment\/graffi_hardwood_flooring_iosa_ghini_listone_giordano\/\" class=\"wp-image-4809\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1024x853.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-300x250.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-768x640.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1536x1280.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-500x417.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Graffi &#8211; design: Massimo Iosa Ghini<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"853\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1-1024x853.jpg\" alt=\"\" data-id=\"4811\" data-link=\"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/attachment\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1\/\" class=\"wp-image-4811\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1-1024x853.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1-300x250.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1-768x640.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1-1536x1280.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1-500x417.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Graffi &#8211; design: Massimo Iosa Ghini<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3-1024x768.jpg\" alt=\"\" data-id=\"4813\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/attachment\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3\/\" class=\"wp-image-4813\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3-1024x768.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3-768x576.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3-1536x1152.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3-500x375.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Graffi &#8211; design: Massimo Iosa Ghini<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni lista di parquet luminoso ha cos\u00ec possibilit\u00e0 di essere integrata perfettamente alla restante pavimentazione, e di arricchire la superficie di un prezioso segno luce con una libert\u00e0 progettuale del tutto inedita. <strong>I listelli incisi, graffiati e illuminati definiscono lo spazio e conferiscono al piano calpestabile la dimensione di  nuovo \u201cteatro\u201d<\/strong>, dove la contrapposizione tra materiale e immateriale, tra staticit\u00e0 del legno e dinamismo dei tagli di luce rivoluzionano e rinnovano il concetto di parquet adattandolo alle pi\u00f9 diverse esigenze d\u2019arredo.\u201d<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La luce, come linfa irradiante, invade la materia donandole nuova vita. Le superfici sono cosi ridisegnate sottolineando la tattilit\u00e0 del Rovere di Fontaines nella sua forma pi\u00f9 pura.<\/p><cite>Massimo Iosa Ghini<\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-8-1024x768.jpg\" alt=\"\" class=\"wp-image-4822\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-8-1024x768.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-8-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-8-768x576.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-8-1536x1151.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-8-500x375.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-8.jpg 1913w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-9-1024x768.jpg\" alt=\"\" class=\"wp-image-4824\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-9-1024x768.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-9-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-9-768x576.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-9-1536x1151.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-9-500x375.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-9.jpg 1913w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/design\/alhambra-marco-tortoioli-ricci\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/alhambra-naturalgenius-listonegiordano-woodflooring-09-500x458.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 7 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/design\/alhambra-marco-tortoioli-ricci\/\" rel=\"bookmark\">Alhambra | Marco Tortoioli Ricci<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/design\/sassi-enzo-calabrese-fabio-meliota\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/sassi_woodflooring_enzo_calabrese_fabio_meliota-3-500x474.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 7 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/design\/sassi-enzo-calabrese-fabio-meliota\/\" rel=\"bookmark\">Sassi | Enzo Calabrese + Fabio Meliota<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/living\/plus-minus-matteo-nunziati\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/12\/plus_minus_woodflooring_matteo_nunziati-5-500x477.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 7 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/living\/plus-minus-matteo-nunziati\/\" rel=\"bookmark\">Plus Minus | Matteo Nunziati<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/design\/il-genio-naturale-del-parquet\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/01\/natural_genius_listone_giordano_guggenheim_02-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/a-margaritelli\/\">Andrea Margaritelli<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 7 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/design\/il-genio-naturale-del-parquet\/\" rel=\"bookmark\">Il Genio Naturale del parquet<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>I listelli, incisi e graffiati, sono sostenuti dalla luce, che come linfa li nutre. Il piano calpestabile acquista cos\u00ec una [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4799,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[4],"tags":[35,48],"class_list":["post-2604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-design","tag-listonegiordano","tag-natural-genius-2"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Graffi | Massimo Iosa Ghini | One Listone Giordano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graffi | Massimo Iosa Ghini\" \/>\n<meta property=\"og:description\" content=\"I listelli, incisi e graffiati, sono sostenuti dalla luce, che come linfa li nutre. Il piano calpestabile acquista cos\u00ec una nuova dimensione, non pi\u00f9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-14T09:47:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-17T10:29:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1736\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/8a45898c971969498387c2725b55454e\"},\"headline\":\"Graffi | Massimo Iosa Ghini\",\"datePublished\":\"2019-06-14T09:47:55+00:00\",\"dateModified\":\"2020-01-17T10:29:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg\",\"keywords\":[\"listonegiordano\",\"naturalgenius\"],\"articleSection\":[\"Design\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/\",\"name\":\"Graffi | Massimo Iosa Ghini | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg\",\"datePublished\":\"2019-06-14T09:47:55+00:00\",\"dateModified\":\"2020-01-17T10:29:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg\",\"width\":1920,\"height\":1736},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/design\\\/graffi-massimo-iosa-ghini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Graffi | Massimo Iosa Ghini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/8a45898c971969498387c2725b55454e\",\"name\":\"Redazione\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/r-listonegiordano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Graffi | Massimo Iosa Ghini | One Listone Giordano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/","og_locale":"it_IT","og_type":"article","og_title":"Graffi | Massimo Iosa Ghini","og_description":"I listelli, incisi e graffiati, sono sostenuti dalla luce, che come linfa li nutre. Il piano calpestabile acquista cos\u00ec una nuova dimensione, non pi\u00f9","og_url":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2019-06-14T09:47:55+00:00","article_modified_time":"2020-01-17T10:29:08+00:00","og_image":[{"width":1920,"height":1736,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/"},"author":{"name":"Redazione","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/8a45898c971969498387c2725b55454e"},"headline":"Graffi | Massimo Iosa Ghini","datePublished":"2019-06-14T09:47:55+00:00","dateModified":"2020-01-17T10:29:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/"},"wordCount":345,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg","keywords":["listonegiordano","naturalgenius"],"articleSection":["Design"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/","url":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/","name":"Graffi | Massimo Iosa Ghini | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg","datePublished":"2019-06-14T09:47:55+00:00","dateModified":"2020-01-17T10:29:08+00:00","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/06\/graffi_hardwood_flooring_iosa_ghini_listone_giordano-6.jpg","width":1920,"height":1736},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/design\/graffi-massimo-iosa-ghini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Graffi | Massimo Iosa Ghini"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/8a45898c971969498387c2725b55454e","name":"Redazione","url":"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/2604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=2604"}],"version-history":[{"count":12,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/2604\/revisions"}],"predecessor-version":[{"id":5464,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/2604\/revisions\/5464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/4799"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=2604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=2604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=2604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}