{"id":5946,"date":"2020-05-12T18:52:03","date_gmt":"2020-05-12T16:52:03","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=5946"},"modified":"2020-06-10T17:10:08","modified_gmt":"2020-06-10T15:10:08","slug":"historic-dwelling-texas-contemporary-interior-design","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/","title":{"rendered":"In Texas l&#8217;interior design rispolvera la sua storia in spirito contemporaneo"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Project 6 Courtlandt Place, Houston Texas<br>Architect, Landscape Architect, and Interior Design by Jerry Hooker \/ Mirador Group<br>General Contractor: Gabriel Home Builders<br>Photography: Divya Pande<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Una villa d\u2019inizio Novecento a Houston<\/strong> torna all\u2019elegante splendore delle origini grazie al restauro di un giovane architetto e al suo propizio incontro con il <strong>Made in Italy<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-11.jpg\" alt=\"interior design \" class=\"wp-image-5800\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-11.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-11-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-11-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-11-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 1909, appena costruita nel nuovissimo quartiere residenziale di <strong>Courtland Place<\/strong> a <strong>Houston<\/strong> dallo studio di architettura <strong>Sanguinet &amp; Staats per C.L. Neuhaus<\/strong> , un noto banchiere della zona, si guadagn\u00f2 l\u2019epiteto di \u201c<strong>casa bianca come una torta nuziale<\/strong>\u201d grazie al suo stile revival coloniale. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ASCOLTA IL PODCAST<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><iframe loading=\"lazy\" src=\"https:\/\/widget.spreaker.com\/player?episode_id=23423234&amp;theme=light&amp;playlist=show&amp;playlist-continuous=false&amp;chapters-image=true&amp;episode_image_position=right&amp;hide-likes=false&amp;hide-comments=false&amp;hide-sharing=false&amp;hide-logo=false&amp;hide-download=true\" width=\"100%\" height=\"350px\" frameborder=\"0\"><\/iframe><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">La villa che <strong>all\u2019inizio del XX secolo era nella periferia verde della citt\u00e0<\/strong> \u2013 la prima eretta in uno dei 26 lotti destinati ad accogliere altrettante mansion per l\u2019establishment della citt\u00e0. <strong>Oggi si trova nella strada privata nel quartiere di Montrose, a due passi da downtown.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-56.jpg\" alt=\"\" data-id=\"5838\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-56.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5838\" class=\"wp-image-5838\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-56.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-56-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-56-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-60.jpg\" alt=\"\" data-id=\"5830\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-60.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5830\" class=\"wp-image-5830\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-60.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-60-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-60-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-59.jpg\" alt=\"\" data-id=\"5832\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-59.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5832\" class=\"wp-image-5832\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-59.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-59-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-59-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-58.jpg\" alt=\"\" data-id=\"5834\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-58.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5834\" class=\"wp-image-5834\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-58.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-58-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-58-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-57.jpg\" alt=\"\" data-id=\"5836\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-57.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5836\" class=\"wp-image-5836\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-57.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-57-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-57-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-55.jpg\" alt=\"\" data-id=\"5840\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-55.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5840\" class=\"wp-image-5840\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-55.jpg 799w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-55-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-55-768x577.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-55-500x375.jpg 500w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-54.jpg\" alt=\"\" data-id=\"5842\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-54.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5842\" class=\"wp-image-5842\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-54.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-54-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-54-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-52.jpg\" alt=\"\" data-id=\"5846\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-52.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5846\" class=\"wp-image-5846\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-52.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-52-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-52-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-51.jpg\" alt=\"\" data-id=\"5848\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-51.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5848\" class=\"wp-image-5848\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-51.jpg 799w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-51-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-51-768x577.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-51-500x375.jpg 500w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>All\u2019inizio del XX secolo Houston<\/strong> era in rapida trasformazione sulla via per diventare una moderna metropoli. Nell\u2019ottica di uno sviluppo urbanistico razionale, si cominci\u00f2 a costruire <strong>nuovi quartieri definiti \u201cprivate places\u201d<\/strong> sullo stile di quelli che avevano avuto tanto successo ad esempio St. Louis, nel Missouri. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Houston era fondata sul commercio e sulla ricchezza di businessmen<\/strong> del cotone, avvocati, compagnie mercantili, e <strong>Courtland Place era nata per loro<\/strong>, che si consideravano socialmente diversi dai magnati del petrolio: vecchia guardia con pedigree e case adeguate. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-53.jpg\" alt=\"interior design \" class=\"wp-image-5802\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-53.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-53-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-53-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cQuesta era disabitata da decenni, in pessime condizioni, circondata da una specie di jungla, ma ce ne siamo innamorati e abbiamo scritto agli eredi perch\u00e9 ce la vendessero.&#8221;<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Cosi Ricorda <strong>Jerry Hooker<\/strong>, che oltre ad essere l\u2019attuale proprietario con <strong>Jacob Sudhoff<\/strong>, dell\u2019edificio al numero 6 di Courtland Place, \u00e8 anche <strong>l\u2019architetto che ne ha curato il restauro nei minimi dettagli<\/strong>.&nbsp; <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-20.jpg\" alt=\"\" data-id=\"5900\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-20.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5900\" class=\"wp-image-5900\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-20.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-20-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-20-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-20-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-24.jpg\" alt=\"\" data-id=\"5892\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-24.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5892\" class=\"wp-image-5892\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-24.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-24-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-24-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-24-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"898\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-23.jpg\" alt=\"\" data-id=\"5894\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-23.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5894\" class=\"wp-image-5894\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-23.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-23-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-23-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-22.jpg\" alt=\"\" data-id=\"5896\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-22.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5896\" class=\"wp-image-5896\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-22.jpg 799w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-22-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-22-768x577.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-22-500x375.jpg 500w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-3.jpg\" alt=\"\" data-id=\"5934\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-3.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5934\" class=\"wp-image-5934\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-3.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-3-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-3-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-3-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-19.jpg\" alt=\"\" data-id=\"5902\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-19.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5902\" class=\"wp-image-5902\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-19.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-19-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-19-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"898\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-18.jpg\" alt=\"\" data-id=\"5904\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-18.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5904\" class=\"wp-image-5904\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-18.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-18-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-18-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-17.jpg\" alt=\"\" data-id=\"5906\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-17.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5906\" class=\"wp-image-5906\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-17.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-17-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-17-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-16.jpg\" alt=\"\" data-id=\"5908\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-16.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5908\" class=\"wp-image-5908\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-16.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-16-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-16-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-16-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-15.jpg\" alt=\"\" data-id=\"5910\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-15.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5910\" class=\"wp-image-5910\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-15.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-15-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-15-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-14.jpg\" alt=\"\" data-id=\"5912\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-14.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5912\" class=\"wp-image-5912\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-14.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-14-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-14-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"898\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-13.jpg\" alt=\"\" data-id=\"5914\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-13.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5914\" class=\"wp-image-5914\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-13.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-13-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-13-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-12.jpg\" alt=\"\" data-id=\"5916\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-12.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5916\" class=\"wp-image-5916\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-12.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-12-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-12-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-12-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-10.jpg\" alt=\"\" data-id=\"5920\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-10.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5920\" class=\"wp-image-5920\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-10.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-10-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-10-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-9.jpg\" alt=\"\" data-id=\"5922\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-9.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5922\" class=\"wp-image-5922\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-9.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-9-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-9-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-9-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-8.jpg\" alt=\"\" data-id=\"5924\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-8.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5924\" class=\"wp-image-5924\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-8.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-8-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-8-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-8-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-7.jpg\" alt=\"\" data-id=\"5926\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-7.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5926\" class=\"wp-image-5926\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-7.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-7-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-7-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-6.jpg\" alt=\"\" data-id=\"5928\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-6.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5928\" class=\"wp-image-5928\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-6.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-6-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-6-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-5.jpg\" alt=\"\" data-id=\"5930\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-5.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5930\" class=\"wp-image-5930\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-5.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-5-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-5-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-5-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-4.jpg\" alt=\"\" data-id=\"5932\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-4.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5932\" class=\"wp-image-5932\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-4.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-4-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-4-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-4-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2.jpg\" alt=\"\" data-id=\"5936\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5936\" class=\"wp-image-5936\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-1.jpg\" alt=\"\" data-id=\"5938\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5938\" class=\"wp-image-5938\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-1.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-1-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-1-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas.jpg\" alt=\"\" data-id=\"5940\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5940\" class=\"wp-image-5940\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ai 600 mq della casa originale<\/strong> \u2013 che aveva una soffitta per la servit\u00f9, un sotterraneo per i locali caldaia e lavanderia; e inoltre la rimessa per le carrozze, la stalla, un pollaio e un ovile, <strong>sono stati aggiunti altri 200 mq circa di dependance. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In oltre due anni di lavori la casa \u00e8 stata riportata allo splendore originale<\/strong>: sono state eliminate le aggiunte incongrue fatte nel tempo , sollevati i pavimenti per consolidare le fondamenta in modo da sostenere la mansion per il prossimo secolo e rifatti tutti i muri.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2.jpg\" alt=\"\" class=\"wp-image-5937\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-2-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Stessa operazione ha riguardato il giardino<\/strong>. Ricondotto il verde entro canoni classici, l\u2019esterno \u00e8 stato dotato di illuminazione \u201carchitettonica\u201d, arredato con pezzi inconfondibili di <strong>made in Italy<\/strong> e sculture dell\u2019artista messicano <strong>Miguel Angel Martin del Campo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ovunque\nsi sente il rumore rilassante dell\u2019acqua, che proviene sia dalla piscina che &nbsp;dalle fontane disseminate nel giardino.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"898\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-39.jpg\" alt=\"interior design \" class=\"wp-image-5804\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-39.jpg 898w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-39-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-39-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-39-500x334.jpg 500w\" sizes=\"auto, (max-width: 898px) 100vw, 898px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cAlla fine il budget \u00e8 raddoppiato ma ne \u00e8 valsa la pena. Il mio \u00e8 stato un restauro onesto, con minime variazioni rispetto al progetto primigenio.&#8221;<\/p><cite>J Hooker<\/cite><\/blockquote>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-41.jpg\" alt=\"\" data-id=\"5868\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-41.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5868\" class=\"wp-image-5868\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-41.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-41-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-41-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-47.jpg\" alt=\"\" data-id=\"5856\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-47.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5856\" class=\"wp-image-5856\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-47.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-47-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-47-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-49.jpg\" alt=\"\" data-id=\"5852\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-49.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5852\" class=\"wp-image-5852\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-49.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-49-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-49-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-46.jpg\" alt=\"\" data-id=\"5858\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-46.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5858\" class=\"wp-image-5858\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-46.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-46-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-46-768x576.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-46-500x375.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-43.jpg\" alt=\"\" data-id=\"5864\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-43.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5864\" class=\"wp-image-5864\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-43.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-43-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-43-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-42.jpg\" alt=\"\" data-id=\"5866\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-42.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5866\" class=\"wp-image-5866\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-42.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-42-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-42-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-40.jpg\" alt=\"\" data-id=\"5870\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-40.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5870\" class=\"wp-image-5870\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-40.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-40-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-40-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-38.jpg\" alt=\"\" data-id=\"5874\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-38.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5874\" class=\"wp-image-5874\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-38.jpg 799w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-38-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-38-768x577.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-38-500x375.jpg 500w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-37.jpg\" alt=\"\" data-id=\"5876\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-37.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5876\" class=\"wp-image-5876\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-37.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-37-300x300.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-37-150x150.jpg 150w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-37-500x500.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-36.jpg\" alt=\"\" data-id=\"5878\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-36.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5878\" class=\"wp-image-5878\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-36.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-36-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-36-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-35.jpg\" alt=\"\" data-id=\"5880\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-35.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5880\" class=\"wp-image-5880\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-35.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-35-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-35-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-34.jpg\" alt=\"\" data-id=\"5882\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-34.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5882\" class=\"wp-image-5882\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-34.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-34-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-34-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-34-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-33.jpg\" alt=\"\" data-id=\"5884\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-33.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5884\" class=\"wp-image-5884\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-33.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-33-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-33-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tra le modifiche, <strong>una master suite \u00e8 stata costruita al piano di sopra della cucina<\/strong>, sul retro, la copertura del passaggio tra la villa e la rimessa che adesso \u00e8 stata convertita in guest house.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"898\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-32.jpg\" alt=\"interior design \" class=\"wp-image-5810\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-32.jpg 898w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-32-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-32-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-32-500x334.jpg 500w\" sizes=\"auto, (max-width: 898px) 100vw, 898px\" \/><\/figure><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cFortunatamente i piani architettonici del 1909 erano molto dettagliati, cos\u00ec abbiamo potuto utilizzarli per ridisegnare le modanature in gesso, i tagli del legno o le balaustre e le cornici.&#8221;<\/p><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"899\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg\" alt=\"interior design \" class=\"wp-image-5806\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg 899w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61-768x513.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61-500x334.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong><a href=\"https:\/\/www.listonegiordano.com\/one\/design\/il-genio-naturale-del-parquet\/\">parquet,<\/a><\/strong> in <strong>rovere francese<\/strong> con una vita di ben 180 anni e delicatamente sbiancato \u00e8 un <strong>Listone Giordano<\/strong>, posato in una elegante <strong>spina francese<\/strong> proprio come in origine. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-44.jpg\" alt=\"interior design \" class=\"wp-image-5808\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-44.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-44-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-44-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gli interni, il progetto di interior \u00e8 sempre di Hooker, prevede un mix di elementi restaurati<\/strong> \u2013 come le maniglie in ottone, camini e le scale \u2013 e particolari progettati in stile, in un dialogo coerente. Una notevole collezione d\u2019arte, messa insieme in anni di viaggi, completa il progetto e rispecchia la forte personalit\u00e0 dei proprietari. <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-67.jpg\" alt=\"\" data-id=\"5820\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-67.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5820\" class=\"wp-image-5820\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-67.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-67-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-67-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-70.jpg\" alt=\"\" data-id=\"5814\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-70.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5814\" class=\"wp-image-5814\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-70.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-70-300x300.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-70-150x150.jpg 150w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-70-500x500.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-68.jpg\" alt=\"\" data-id=\"5818\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-68.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5818\" class=\"wp-image-5818\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-68.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-68-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-68-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-69.jpg\" alt=\"\" data-id=\"5816\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-69.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5816\" class=\"wp-image-5816\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-69.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-69-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-69-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"899\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-66.jpg\" alt=\"\" data-id=\"5822\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-66.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5822\" class=\"wp-image-5822\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-66.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-66-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-66-334x500.jpg 334w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"600\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-63.jpg\" alt=\"\" data-id=\"5828\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-63.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5828\" class=\"wp-image-5828\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-63.jpg 799w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-63-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-63-768x577.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-63-500x375.jpg 500w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-64.jpg\" alt=\"\" data-id=\"5826\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-64.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5826\" class=\"wp-image-5826\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-64.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-64-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-64-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-65.jpg\" alt=\"\" data-id=\"5824\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-65.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/en\/?attachment_id=5824\" class=\"wp-image-5824\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-65.jpg 600w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-65-225x300.jpg 225w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-65-375x500.jpg 375w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Si ringrazia per la pubblicazione <strong><a href=\"https:\/\/www.architecturaldigest.com\/story\/after-miserably-failing-inspection-a-houston-home-became-a-labor-of-love-project-for-jerry-hooker\">Architectural Digest<\/a><\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si ringrazia il nostro partner <a href=\"https:\/\/www.casa-houston.com\/\">Casa Houston<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/citylife_zaha_hadid_woodfloor-40-1-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\">Penthouse One-11: la sinuosa torre di comando Zaha Hadid a Citylife<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/villa-criss-cross\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2018\/12\/Villa_Criss_Cross_listone_giordano_architettura-00-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/villa-criss-cross\/\" rel=\"bookmark\">Villa Criss Cross: una nuova pelle abbraccia la villa di Lubiana<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/museo-pieta-rondanini\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/01\/pieta_rondanini_listone_giordano_architettura-01-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 7 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/museo-pieta-rondanini\/\" rel=\"bookmark\">La Piet\u00e0 Rondanini prende un posto d\u2019onore a Castello Sforzesco<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/villa-bled\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2018\/12\/Villa_Bled_listone_giordano_architettura-00-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 7 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/villa-bled\/\" rel=\"bookmark\">Villa Bled: Il fascino  intramontabile di una villa sul lago di Bled<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Project 6 Courtlandt Place, Houston TexasArchitect, Landscape Architect, and Interior Design by Jerry Hooker \/ Mirador GroupGeneral Contractor: Gabriel Home [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":5807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[2],"tags":[52],"class_list":["post-5946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura","tag-listone-giordano"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>In Texas l&#039;interior design rispolvera la sua storia in spirito contemporaneo | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Una villa d\u2019inizio Novecento a Houston, Texas torna all\u2019elegante splendore delle origini grazie a un interior design tutto made in italy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Texas l&#039;interior design rispolvera la sua storia in spirito contemporaneo\" \/>\n<meta property=\"og:description\" content=\"Project 6 Courtlandt Place, Houston TexasArchitect, Landscape Architect, and Interior Design by Jerry Hooker \/ Mirador GroupGeneral Contractor: Gabriel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-12T16:52:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-10T15:10:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"899\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Debora Vella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Debora Vella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/\"},\"author\":{\"name\":\"Debora Vella\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/f51ca90669d11c0686d559f6d2a4a54d\"},\"headline\":\"In Texas l&#8217;interior design rispolvera la sua storia in spirito contemporaneo\",\"datePublished\":\"2020-05-12T16:52:03+00:00\",\"dateModified\":\"2020-06-10T15:10:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/\"},\"wordCount\":662,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/interior_design_texas-61.jpg\",\"keywords\":[\"listone giordano\"],\"articleSection\":[\"Architettura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/\",\"name\":\"In Texas l'interior design rispolvera la sua storia in spirito contemporaneo | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/interior_design_texas-61.jpg\",\"datePublished\":\"2020-05-12T16:52:03+00:00\",\"dateModified\":\"2020-06-10T15:10:08+00:00\",\"description\":\"Una villa d\u2019inizio Novecento a Houston, Texas torna all\u2019elegante splendore delle origini grazie a un interior design tutto made in italy.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/interior_design_texas-61.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/interior_design_texas-61.jpg\",\"width\":899,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/historic-dwelling-texas-contemporary-interior-design\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In Texas l&#8217;interior design rispolvera la sua storia in spirito contemporaneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/f51ca90669d11c0686d559f6d2a4a54d\",\"name\":\"Debora Vella\",\"sameAs\":[\"http:\\\/\\\/www.listonegiordano.com\"],\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/debora\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In Texas l'interior design rispolvera la sua storia in spirito contemporaneo | One Listone Giordano","description":"Una villa d\u2019inizio Novecento a Houston, Texas torna all\u2019elegante splendore delle origini grazie a un interior design tutto made in italy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/","og_locale":"it_IT","og_type":"article","og_title":"In Texas l'interior design rispolvera la sua storia in spirito contemporaneo","og_description":"Project 6 Courtlandt Place, Houston TexasArchitect, Landscape Architect, and Interior Design by Jerry Hooker \/ Mirador GroupGeneral Contractor: Gabriel","og_url":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2020-05-12T16:52:03+00:00","article_modified_time":"2020-06-10T15:10:08+00:00","og_image":[{"width":899,"height":600,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg","type":"image\/jpeg"}],"author":"Debora Vella","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Debora Vella","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/"},"author":{"name":"Debora Vella","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/f51ca90669d11c0686d559f6d2a4a54d"},"headline":"In Texas l&#8217;interior design rispolvera la sua storia in spirito contemporaneo","datePublished":"2020-05-12T16:52:03+00:00","dateModified":"2020-06-10T15:10:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/"},"wordCount":662,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg","keywords":["listone giordano"],"articleSection":["Architettura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/","url":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/","name":"In Texas l'interior design rispolvera la sua storia in spirito contemporaneo | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg","datePublished":"2020-05-12T16:52:03+00:00","dateModified":"2020-06-10T15:10:08+00:00","description":"Una villa d\u2019inizio Novecento a Houston, Texas torna all\u2019elegante splendore delle origini grazie a un interior design tutto made in italy.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/01\/interior_design_texas-61.jpg","width":899,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/historic-dwelling-texas-contemporary-interior-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"In Texas l&#8217;interior design rispolvera la sua storia in spirito contemporaneo"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/f51ca90669d11c0686d559f6d2a4a54d","name":"Debora Vella","sameAs":["http:\/\/www.listonegiordano.com"],"url":"https:\/\/www.listonegiordano.com\/one\/author\/debora\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/5946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=5946"}],"version-history":[{"count":28,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/5946\/revisions"}],"predecessor-version":[{"id":7683,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/5946\/revisions\/7683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/5807"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=5946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=5946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=5946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}