{"id":6853,"date":"2020-04-08T11:22:49","date_gmt":"2020-04-08T09:22:49","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=6853"},"modified":"2020-04-09T11:11:27","modified_gmt":"2020-04-09T09:11:27","slug":"palazzo-poste-a-verona-rinasce-nel-culto-dellarte","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/","title":{"rendered":"Palazzo Poste a Verona rinasce nel culto dell\u2019arte"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><em>Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un&#8217;iniziativa residenziale all\u2019insegna dell\u2019arte e del design.<\/em><\/h4>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-45-683x1024.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-6955\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-45-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-45-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-45-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-45-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-45.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nel cuore della romantica citt\u00e0 di Romeo e Giulietta<\/strong>, si erge maestoso una storico palazzo memore degli agli anni venti, progettato da&nbsp;<strong>Ettore Fagiuoli,&nbsp;<\/strong>architetto della sede della Banca d\u2019Italia in via Cordusio a Milano, in collaborazione con Broggi e Nava, e del campanile per il <strong>Duomo di Verona <\/strong>realizzato nel 1927. <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-18.jpg\" alt=\"\" data-id=\"7009\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-18.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=7009\" class=\"wp-image-7009\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-18.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-18-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-18-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-18-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"915\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-17-1.jpg\" alt=\"\" data-id=\"6957\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-17-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6957\" class=\"wp-image-6957\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-17-1.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-17-1-262x300.jpg 262w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-17-1-768x878.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-17-1-437x500.jpg 437w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg\" alt=\"\" data-id=\"6959\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6959\" class=\"wp-image-6959\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-41-683x1024.jpg\" alt=\"\" data-id=\"6963\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-41.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6963\" class=\"wp-image-6963\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-41-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-41-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-41-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-41-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-41.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-40.jpg\" alt=\"\" data-id=\"6965\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-40.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6965\" class=\"wp-image-6965\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-40.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-40-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-40-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-40-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-39.jpg\" alt=\"\" data-id=\"6967\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-39.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6967\" class=\"wp-image-6967\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-39.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-39-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-39-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-39-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-38.jpg\" alt=\"\" data-id=\"6969\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-38.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6969\" class=\"wp-image-6969\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-38.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-38-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-38-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-38-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-36.jpg\" alt=\"\" data-id=\"6973\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-36.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6973\" class=\"wp-image-6973\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-36.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-36-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-36-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-36-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-35.jpg\" alt=\"\" data-id=\"6975\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-35.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6975\" class=\"wp-image-6975\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-35.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-35-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-35-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-35-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-32.jpg\" alt=\"\" data-id=\"6981\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-32.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6981\" class=\"wp-image-6981\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-32.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-32-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-32-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-32-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-31-683x1024.jpg\" alt=\"\" data-id=\"6983\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-31.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6983\" class=\"wp-image-6983\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-31-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-31-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-31-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-31-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-31.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-30-683x1024.jpg\" alt=\"\" data-id=\"6985\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-30.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6985\" class=\"wp-image-6985\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-30-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-30-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-30-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-30-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-30.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-29.jpg\" alt=\"\" data-id=\"6987\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-29.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6987\" class=\"wp-image-6987\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-29.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-29-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-29-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-29-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-28.jpg\" alt=\"\" data-id=\"6989\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-28.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6989\" class=\"wp-image-6989\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-28.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-28-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-28-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-28-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-27-683x1024.jpg\" alt=\"\" data-id=\"6991\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-27.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6991\" class=\"wp-image-6991\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-27-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-27-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-27-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-27-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-27.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-26.jpg\" alt=\"\" data-id=\"6993\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-26.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6993\" class=\"wp-image-6993\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-26.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-26-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-26-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-26-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-25.jpg\" alt=\"\" data-id=\"6995\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-25.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6995\" class=\"wp-image-6995\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-25.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-25-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-25-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-25-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-24-683x1024.jpg\" alt=\"\" data-id=\"6997\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-24.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6997\" class=\"wp-image-6997\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-24-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-24-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-24-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-24-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-24.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-23-683x1024.jpg\" alt=\"\" data-id=\"6999\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-23.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=6999\" class=\"wp-image-6999\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-23-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-23-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-23-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-23-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-23.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-22-683x1024.jpg\" alt=\"\" data-id=\"7001\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-22.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=7001\" class=\"wp-image-7001\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-22-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-22-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-22-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-22-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-22.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"537\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-21.jpg\" alt=\"\" data-id=\"7003\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-21.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=7003\" class=\"wp-image-7003\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-21.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-21-300x201.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-21-768x516.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-21-500x336.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"601\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-20.jpg\" alt=\"\" data-id=\"7005\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-20.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=7005\" class=\"wp-image-7005\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-20.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-20-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-20-768x577.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-20-500x376.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-19.jpg\" alt=\"\" data-id=\"7007\" data-full-url=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-19.jpg\" data-link=\"https:\/\/www.listonegiordano.com\/one\/?attachment_id=7007\" class=\"wp-image-7007\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-19.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-19-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-19-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-19-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La memoria storica ce lo&nbsp;consegna con il nome di &nbsp;\u201c<strong>Palazzo Poste<\/strong>\u201d, esempio d\u2019ispirazione manieristica e barocca, capace di esprimere contemporaneamente decoro e sobriet\u00e0. In questi ultimi anni ha conosciuto una nuova giovinezza, frutto dell\u2019ambizioso progetto di restauro e trasformazione a cui \u00e8 stato sottoposto. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/74211278_751173695310041_3815993475157983232_o-1024x683.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7029\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/74211278_751173695310041_3815993475157983232_o-1024x683.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/74211278_751173695310041_3815993475157983232_o-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/74211278_751173695310041_3815993475157983232_o-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/74211278_751173695310041_3815993475157983232_o-1536x1024.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/74211278_751173695310041_3815993475157983232_o-500x333.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/74211278_751173695310041_3815993475157983232_o.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Per consolidare lo stretto legame dello storico palazzo con l&#8217;arte \u00e8 stata esposta la leggendaria e misteriosa opera&nbsp;<a href=\"https:\/\/www.listonegiordano.com\/one\/cultura\/storia-del-bambin-gesu-delle-mani-del-pinturicchio\/\"><em>Il Bambin Ges\u00f9 delle Mani<\/em>&nbsp;<\/a>del&nbsp;<strong>Pinturicchio<\/strong>, raccontata da&nbsp;<strong>Andrea Margaritelli<\/strong>, presidente della&nbsp;<strong><a href=\"http:\/\/www.fondazionegiordano.org\/\">Fondazione Guglielmo Giordano<\/a><\/strong> proprietaria dell\u2019opera. <\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Palazzo Poste a Verona rinasce -  Milano Contract District\" width=\"960\" height=\"540\" src=\"https:\/\/www.youtube.com\/embed\/FAY-vjPB-_M?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/www.listonegiordano.com\/one\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sempre negli stessi spazi durante la cerimonia di apertura \u00e8 stato esposto il capolavoro del maestro Giorgio de Chirico \u201c<strong>\u00abLa commedia e la tragedia\u00bb dipinto nel 1926 e riconosciuto tra i pi\u00f9 alti esempi di arte metafisica.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-13.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7011\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-13.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-13-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-13-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-13-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019attenta attivit\u00e0 di recupero intrapresa da&nbsp;<strong>Abitare Co.<\/strong>, societ\u00e0 specializzata nell\u2019intermediazione immobiliare, lo ha portato ad assumere un nuovo ruolo e posizionamento nell\u2019immaginario comune dei cittadini veronesi e non solo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-12.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7013\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-12.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-12-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-12-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-12-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La model home, il pi\u00f9 prestigioso degli appartamenti, si veste di un <strong>parquet Listone Giordano<\/strong> di alta sartoria realizzato su misura, da <strong><a href=\"https:\/\/bordonivr.it\/\">Bordoni Tuttoparquet<\/a><\/strong>, in <a href=\"https:\/\/www.listonegiordano.com\/it\/atelier\/collezione\/heritage-filigrana\"><strong>Heritage Siena Filigrana<\/strong><\/a> con una posa particolare &#8220;a pettine&#8221; che incrocia sapientemente tagli verticali ed orizzontali.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-14.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7025\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-14.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-14-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-14-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-14-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A collaborare per riposizionare il building nell\u2019immaginario comune come nuova residenza, ora di propriet\u00e0 del fondo&nbsp;<strong>Aquileia Capital Services<\/strong>, anche&nbsp;<strong><a href=\"https:\/\/contract-district.com\/\">Milano Contract District<\/a><\/strong>, <strong>la prima Interior Design Platform al mondo<\/strong>, insignita della Menzione d\u2019Onore all\u2019edizione 2018 dell\u2019<strong>ADI Compasso d\u2019Oro<\/strong>, che ha curato il servizio di interior design con un pacchetto esclusivo di prodotti e servizi che si sono spinti fino all\u2019art direction ed il progetto dello showroom che \u00e8 stato realizzato da&nbsp;<strong>Tecma Solutions<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-16-683x1024.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7015\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-16-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-16-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-16-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-16-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-16.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-9.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7027\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-9.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-9-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-9-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-9-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un\u2019iniziativa che porta alla rinascita dello storico edificio attraverso la proposta di&nbsp;<strong>venti unit\u00e0 abitative<\/strong>, uniche ed esclusive nel loro genere. Le nuove residenze si compongono di plurilocali con terrazzo e particolari altane private,&nbsp;<strong>fino ad appartamenti di piccolo taglio<\/strong>, adatti ad un target di investitori, tutti su&nbsp;<strong>misura<\/strong>,&nbsp;<strong>personalizzabili<\/strong>&nbsp;e con&nbsp;<strong>servizi innovativi<\/strong>&nbsp;che vanno dalla Conciergerie, alla Spa e alla Palestra, offendo anche spazi di Co-working e un\u2019area di Food &amp; Delivery Storage a disposizione dei futuri residenti.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-5.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7017\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-5.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-5-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-5-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-5-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-8.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7023\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-8.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-8-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-8-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-8-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cIl mercato immobiliare di Verona ha registrato lo scorso anno una crescita del 5,2% di compravendite, sintomo di un territorio vivace, che deve per\u00f2 fare fronte, in particolare per gli immobili di fascia alta, ad una domanda sempre pi\u00f9 esigente<\/em>&nbsp;\u2013 ha dichiarato&nbsp;<strong>Giuseppe Crupi, amministratore unico di Abitare Co.<\/strong>&nbsp;\u2013&nbsp;<em>I nuovi appartamenti di Palazzo Poste rispondono all\u2019evoluzione delle abitudini di acquisto, offrendo non solo gli ultimi trend dell\u2019interior design di pregio, sempre pi\u00f9 protagonista, ma un\u2019ampia gamma di servizi unici ed esclusivi, pensati per venire incontro alle richieste degli acquirenti e del loro stile di vita, con l\u2019obiettivo di dare il massimo comfort abitativo\u201d.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-6.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7019\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-6.jpg 800w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-6-300x200.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-6-768x512.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-6-500x333.jpg 500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Dopo Milano, Roma e Torino, portiamo il know how e\nl\u2019expertise di Milano Contract District anche a Verona in un progetto di riqualificazione\niconico per il capoluogo veneto<\/em>&nbsp;\u2013 ha dichiarato&nbsp;<strong>Lorenzo\nPascucci, CEO di MCD&nbsp;<\/strong>\u2013&nbsp;<em>Milano Contract District, con la sua\nofferta di prodotti e servizi esclusivi, ha saputo anche in questo caso\nincontrare l\u2019esigenza del committente, attraverso un processo integrato di\nstudio e di soluzioni che ha consentito di riposizionare sul mercato un\nedificio di grande pregio e storia partendo dall\u2019interior design<\/em>.\u201d<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-10-683x1024.jpg\" alt=\"Palazzo Poste Verona\" class=\"wp-image-7021\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-10-683x1024.jpg 683w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-10-200x300.jpg 200w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-10-768x1152.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-10-333x500.jpg 333w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-10.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tra i brand partner di MCD che aderiscono al progetto, <strong>Gessi<\/strong>, <strong>Fontanot<\/strong>, <strong>Listone Giordano<\/strong>, <strong>Florim<\/strong>, <strong>Lualdi<\/strong>, <strong>Lema<\/strong> e <strong>Flos<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/citylife_zaha_hadid_woodfloor-40-1-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\">Penthouse One-11: la sinuosa torre di comando Zaha Hadid a Citylife<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/boutique-del-lusso-una-brillante-mise-en-scene-per-bucherer-a-monaco\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/image018-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/boutique-del-lusso-una-brillante-mise-en-scene-per-bucherer-a-monaco\/\" rel=\"bookmark\">Boutique del lusso: una brillante mise en sc\u00e8ne per Bucherer a Monaco<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/steven-holl-daeyang-gallery-and-house\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2018\/11\/Daeyang_Gallery_listone_giordano_architettura-00-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/steven-holl-daeyang-gallery-and-house\/\" rel=\"bookmark\">Daeyang Gallery and House: i mille riflessi della casa galleria d\u2019arte firmata da Steven Holl<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/432-park-avenue-il-design-italiano-ad-alta-quota\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/03\/Living-vista-2-500x387.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/r-listonegiordano\/\">Redazione<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/432-park-avenue-il-design-italiano-ad-alta-quota\/\" rel=\"bookmark\">432 Park Avenue: il design italiano ad alta quota<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un&#8217;iniziativa residenziale all\u2019insegna dell\u2019arte e del [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-6853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Palazzo Poste a Verona rinasce nel culto dell\u2019arte | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un&#039;iniziativa residenziale all\u2019insegna dell\u2019arte e del design.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palazzo Poste a Verona rinasce nel culto dell\u2019arte\" \/>\n<meta property=\"og:description\" content=\"Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un&#039;iniziativa residenziale all\u2019insegna dell\u2019arte e del design. Nel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-08T09:22:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-09T09:11:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Debora Vella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Debora Vella\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/\"},\"author\":{\"name\":\"Debora Vella\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/f51ca90669d11c0686d559f6d2a4a54d\"},\"headline\":\"Palazzo Poste a Verona rinasce nel culto dell\u2019arte\",\"datePublished\":\"2020-04-08T09:22:49+00:00\",\"dateModified\":\"2020-04-09T09:11:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/\"},\"wordCount\":684,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/palazzo_poste_verona-43-1.jpg\",\"articleSection\":[\"Architettura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/\",\"name\":\"Palazzo Poste a Verona rinasce nel culto dell\u2019arte | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/palazzo_poste_verona-43-1.jpg\",\"datePublished\":\"2020-04-08T09:22:49+00:00\",\"dateModified\":\"2020-04-09T09:11:27+00:00\",\"description\":\"Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un'iniziativa residenziale all\u2019insegna dell\u2019arte e del design.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/palazzo_poste_verona-43-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/palazzo_poste_verona-43-1.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palazzo Poste a Verona rinasce nel culto dell\u2019arte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/f51ca90669d11c0686d559f6d2a4a54d\",\"name\":\"Debora Vella\",\"sameAs\":[\"http:\\\/\\\/www.listonegiordano.com\"],\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/debora\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Palazzo Poste a Verona rinasce nel culto dell\u2019arte | One Listone Giordano","description":"Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un'iniziativa residenziale all\u2019insegna dell\u2019arte e del design.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/","og_locale":"it_IT","og_type":"article","og_title":"Palazzo Poste a Verona rinasce nel culto dell\u2019arte","og_description":"Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un'iniziativa residenziale all\u2019insegna dell\u2019arte e del design. Nel","og_url":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2020-04-08T09:22:49+00:00","article_modified_time":"2020-04-09T09:11:27+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg","type":"image\/jpeg"}],"author":"Debora Vella","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Debora Vella","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/"},"author":{"name":"Debora Vella","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/f51ca90669d11c0686d559f6d2a4a54d"},"headline":"Palazzo Poste a Verona rinasce nel culto dell\u2019arte","datePublished":"2020-04-08T09:22:49+00:00","dateModified":"2020-04-09T09:11:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/"},"wordCount":684,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg","articleSection":["Architettura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/","url":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/","name":"Palazzo Poste a Verona rinasce nel culto dell\u2019arte | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg","datePublished":"2020-04-08T09:22:49+00:00","dateModified":"2020-04-09T09:11:27+00:00","description":"Palazzo Poste a Verona, progettato da Ettore Fagiuoli negli anni \u201920, rinasce grazie a un'iniziativa residenziale all\u2019insegna dell\u2019arte e del design.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/palazzo_poste_verona-43-1.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/palazzo-poste-a-verona-rinasce-nel-culto-dellarte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Palazzo Poste a Verona rinasce nel culto dell\u2019arte"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/f51ca90669d11c0686d559f6d2a4a54d","name":"Debora Vella","sameAs":["http:\/\/www.listonegiordano.com"],"url":"https:\/\/www.listonegiordano.com\/one\/author\/debora\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/6853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=6853"}],"version-history":[{"count":8,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/6853\/revisions"}],"predecessor-version":[{"id":7040,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/6853\/revisions\/7040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/6959"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=6853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=6853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=6853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}