{"id":9502,"date":"2020-08-05T15:30:24","date_gmt":"2020-08-05T13:30:24","guid":{"rendered":"https:\/\/one.listonegiordano.com\/?p=9502"},"modified":"2021-02-16T17:55:30","modified_gmt":"2021-02-16T16:55:30","slug":"lina-bo-bardi","status":"publish","type":"post","link":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/","title":{"rendered":"Lina Bo Bardi, &#8220;il Brasile \u00e8 il paese dove voglio vivere&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica, un progetto esistenziale, sentimentale e professionale globale come <strong>Lina Bo Bardi<\/strong>, la sua parabola cresce, si costruisce nell\u2019 Italia fascista, dalla laurea nel 1939 a Roma, alle prime esperienze milanesi, dove arriva nei primi anni \u201940.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partire da <strong>Gio Ponti<\/strong> con cui si forma e dunque con l\u2019incontro con quello che rappresenta uno dei pi\u00f9 importanti critici d\u2019arte dell\u2019epoca, quell\u2019autore della \u201ctavola degli orrori\u201d che nel 1933 mette alla berlina le forme pi\u00f9 accademiche dell\u2019architettura italiana, naturalmente inascoltato.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cvieni c\u2019\u00e8 una strada nel bosco, il suo nome conosco\u201d<\/em><\/p><p><em>\u201cC&#8217;\u00e8 un gusto di vittoria e di meraviglia nell&#8217;essere semplici. &#8220;<\/em><\/p><p><em>\u201cLa produzione di massa, che oggi deve essere presa in considerazione come base per l&#8217;architettura moderna, esiste nella stessa Natura e, intuitivamente, nell&#8217;opera popolare.\u201d<\/em><\/p><cite><em>Achillina Bo<\/em><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pietro Maria Bardi<\/strong> \u00e8 l\u2019uomo e il compagno di una vita, l\u2019artefice del suo destino, cinquanta anni in simbiosi, eccola la perfetta rappresentazione di una &nbsp;professionista moderna, instancabile, curiosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ASCOLTA IL PODCAST<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><iframe loading=\"lazy\" src=\"https:\/\/widget.spreaker.com\/player?episode_id=40422858&amp;theme=light&amp;playlist=show&amp;playlist-continuous=false&amp;chapters-image=true&amp;episode_image_position=right&amp;hide-likes=false&amp;hide-comments=false&amp;hide-sharing=false&amp;hide-logo=false&amp;hide-download=true\" width=\"100%\" height=\"350px\" frameborder=\"0\"><\/iframe><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Milano<\/strong>, nonostante guerre, conflitti, condizioni generali molto complicate, vive un entusiasmo e una strana frenesia <strong>dove si concretizzano alcuni dei progetti di architettura pi\u00f9 importanti del secolo<\/strong>, mentre Lina stessa lavora ad alcune grandi riviste indimenticabili.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/bo-bardi-intro-1_525.jpg\" alt=\"Lina Bo Bardi\" class=\"wp-image-9510\" loading=\"lazy\" \/><figcaption>Lina Bo Bardi<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La conoscenza di Ponti la porta a <em>Domus<\/em><\/strong>, di cui diventa co-direttrice con Carlo Pagani, e a Stile lavora anche per <em>L\u2019Illustrazione Italiana<\/em> e nel 1943 fonda <em>A-Attualit\u00e0, Architettura, Abitazione, Arte,<\/em> con il supporto di Bruno Zevi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il suo studio di via Ges\u00f9 viene distrutto, e a quel punto col marito, immagina un cambiamento totale di vita, di professione, lontano dall\u2019Italia e per sempre, altrove nella storia e nel mondo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/nel-cielo-stellato-di-zaha-hadid\/\">Nel cielo stellato di Zaha Hadid<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quando arrivano a San Paolo<\/strong>, invitati dal mecenate e collezionista Assis Chateaubriand, <strong>devono costruire un museo<\/strong>, inventarlo, creare una collezione e scegliere il meglio dell\u2019arte europea, e su questo Bardi \u00e8 molto competente, ma ancora non sa che sar\u00e0 sua moglie a inventare \u201cl\u2019architettura paulista\u201d, perch\u00e9 sar\u00e0 <strong>Lina a dedicare tante energie al pi\u00f9 importante museo del Sud-America d\u2019Arte Contemporanea<\/strong>, mai realizzato.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/lina-bo-bardi-come-una-donna-rivoluzionato-architettura-design-1024x576.jpg\" alt=\"Lina Bo Bardi -  S\u00e3o Paulo Museum of Art (MASP). Image \u00a9 Pedro Kok\" class=\"wp-image-9508\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/lina-bo-bardi-come-una-donna-rivoluzionato-architettura-design-1024x576.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/lina-bo-bardi-come-una-donna-rivoluzionato-architettura-design-300x169.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/lina-bo-bardi-come-una-donna-rivoluzionato-architettura-design-768x432.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/lina-bo-bardi-come-una-donna-rivoluzionato-architettura-design-1536x864.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/lina-bo-bardi-come-una-donna-rivoluzionato-architettura-design-500x281.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/lina-bo-bardi-come-una-donna-rivoluzionato-architettura-design.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>S\u00e3o Paulo Museum of Art (MASP). Image \u00a9 Pedro Kok<\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cIl tempo lineare \u00e8 un&#8217;invenzione dell&#8217;Occidente. Il tempo non \u00e8 lineare, \u00e8 un meraviglioso groviglio dove, in qualsiasi momento, possiamo scegliere punti e inventare soluzioni, senza inizio e senza fine.\u201d<\/em><\/p><p><em>\u201cIl passato non ritorna. Sono importanti la continuit\u00e0 e la conoscenza perfetta della propria storia.\u201d<\/em><\/p><cite><em>Achillina Bo<\/em><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Il lavoro dell\u2019architetta romana, diventa quasi omologo al suo impegno culturale, sociale, antropologico, in quegli anni il sodalizio col marito-mecenate-gallerista e futuro direttore del MASP diventa talmente identitario da non avere eguali nei percorsi simili di quegli anni meravigliosi a partire dal lavoro alla facolt\u00e0 di architettura di San Paolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Non \u00e8 solo design modernista<\/strong>, non sono mostre o allestimenti, <strong>nasce un modo di pensare diverso<\/strong>, la contemporaneit\u00e0 che ha nel genio carioca di Niemeyer l\u2019altro versante, diventa l\u2019altra faccia della medaglia,<strong> l\u2019approdo di un\u2019altra modernit\u00e0 che non sar\u00e0 mai contemporaneit\u00e0<\/strong>, cos\u00ec incastrata concettualmente nelle vecchie avanguardie europee.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/01_linabobardi_exhibition_image_francisco_albuquerque_1950_full-1024x608.jpg\" alt=\"Mostra Lina Bo Bardi 100 - Brazil\u2019s Alternative Path to Modernism\" class=\"wp-image-9512\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/01_linabobardi_exhibition_image_francisco_albuquerque_1950_full-1024x608.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/01_linabobardi_exhibition_image_francisco_albuquerque_1950_full-300x178.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/01_linabobardi_exhibition_image_francisco_albuquerque_1950_full-768x456.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/01_linabobardi_exhibition_image_francisco_albuquerque_1950_full-1536x911.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/01_linabobardi_exhibition_image_francisco_albuquerque_1950_full-500x297.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/01_linabobardi_exhibition_image_francisco_albuquerque_1950_full.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Mostra Lina Bo Bardi 100 &#8211; Brazil\u2019s Alternative Path to Modernism<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il Brasile \u00e8 il paese dove Lina Bo diventa concretamente progettista\/architetta<\/strong>, assorbe una visione della societ\u00e0 in formazione e compie le scelte che l\u2019estetica deve ad una partecipazione culturale, nuova, ed \u00e8 tutto cos\u00ec fortemente europeo, ma totalmente lontano, distante dai luoghi d\u2019origine, Milano o Roma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La nostra architettrice \u00e8 pronta per uno dei suoi progetti che cambieranno la storia di una particolare idea di razionalismo brutalista<\/strong>, neo-sociale (non dimentichiamo la sua antica militanza anche in tempi non sospetti), nel senso pi\u00f9 profondo, dove la costruzione dell\u2019architettura definisce lo scenario pi\u00f9 impegnato e condiviso, dove committenza, utenza e progettazione condividono il sogno di una societ\u00e0 libera e solidale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cos\u00ec lontana, cos\u00ec diversa, cos\u00ec brasiliana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanti momenti diversi, ma tutti vicini ad un\u2019idea assoluta di progettazione che ha nel cuore il centro esatto dell\u2019emozione: <strong>La casa di vetro<\/strong>,<strong> il Museo di San Paolo, il grande lavoro urbanistico a San Salvador de Baia, e i lavori della maturit\u00e0, al ritorno a San Paolo<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"694\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/06_Teatro-Oficina-Lina-Bo-Bardi-Edson-Elito-Image-\u00a9-Nelson-Kon-1024x694.jpg\" alt=\"Teatro Oficina Lina Bo Bardi &amp; Edson Elito Image \u00a9 Nelson Kon\" class=\"wp-image-9514\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/06_Teatro-Oficina-Lina-Bo-Bardi-Edson-Elito-Image-\u00a9-Nelson-Kon-1024x694.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/06_Teatro-Oficina-Lina-Bo-Bardi-Edson-Elito-Image-\u00a9-Nelson-Kon-300x203.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/06_Teatro-Oficina-Lina-Bo-Bardi-Edson-Elito-Image-\u00a9-Nelson-Kon-768x520.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/06_Teatro-Oficina-Lina-Bo-Bardi-Edson-Elito-Image-\u00a9-Nelson-Kon-500x339.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/06_Teatro-Oficina-Lina-Bo-Bardi-Edson-Elito-Image-\u00a9-Nelson-Kon.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Teatro Oficina Lina Bo Bardi &amp; Edson Elito Image \u00a9 Nelson Kon<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lina Bo bardi dedica un decennio ad ogni progetto<\/strong>, manifestazioni eponime di un suo particolare vocabolario delle forme, delle elaborazioni estetiche, molta antropologia culturale e riduzione all\u2019essenziale delle funzioni, il suo programma \u00e8 preciso, il suo obiettivo \u00e8 il Brasile come metafora del mondo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nella casa di Vetro c\u2019\u00e8 lo spazio della vita<\/strong>, il luogo dove il teatro dell\u2019esistenza si manifesta, diventa un\u2019architettura, un pezzo di natura, di citt\u00e0, antichissima e modernissima, <strong>Lina e Pietro costruiscono la metafora della loro spiritualit\u00e0 sociale<\/strong>, ed hanno un paese intero per poterlo realizzare , dunque \u201ca Casa\u201d \u00e8 il posto da cui non si potr\u00e0 pi\u00f9 partire ma solo ritornare, un approdo sicuro: vita e professione si equivalgono, politica e passione si sostengono.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/donne-e-architettura-qualche-secolo-di-discriminazioni-derisioni-incomprensioni-isolamenti-e-luoghi-comuni\/\">Donne e architettura, qualche secolo di discriminazioni, derisioni, incomprensioni, isolamenti e luoghi comuni<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Niente da dichiarare, mezzo secolo da ricordare, <strong>in un lampo il razionalismo colorato torna essenza<\/strong>, si avviluppa in una impossibilit\u00e0, non cede al senso, non sente, non vive nel sentimento dello spazio che possiamo condividere con altri.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"635\" height=\"450\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lallestimento-di-Lina-Bo-Bardi-Museu-de-Arte-de-Sa\u0303o-Paulo-1968.jpg\" alt=\"L'allestimento di Lina Bo Bardi, Museu de Arte de S\u00e3o Paulo, 1968\" class=\"wp-image-9516\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lallestimento-di-Lina-Bo-Bardi-Museu-de-Arte-de-Sa\u0303o-Paulo-1968.jpg 635w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lallestimento-di-Lina-Bo-Bardi-Museu-de-Arte-de-Sa\u0303o-Paulo-1968-300x213.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lallestimento-di-Lina-Bo-Bardi-Museu-de-Arte-de-Sa\u0303o-Paulo-1968-500x354.jpg 500w\" sizes=\"auto, (max-width: 635px) 100vw, 635px\" \/><figcaption>L&#8217;allestimento di Lina Bo Bardi, Museu de Arte de S\u00e3o Paulo, 1968<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 amore, \u00e8 un tempo infinito da condividere fino alla fine, per raccogliere tutte le cose, belle o brutte di cui circondarsi, di tramonti, e albe e altre armonie segrete per dare all\u2019architettura il senso compiuto che si merita, solo per chi ci ama e per chi amiamo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ora \u201cdonna Lina\u201d \u00e8 pronta per il Masp di San Paolo<\/strong>, un grattacielo orizzontale sull\u2019Avenida Paulista, un cratere di cemento armato sospeso da terra otto metri e catapultato verso l\u2019idea pi\u00f9 pura di spazio culturale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Una piazza al di sotto del museo per far vivere la citt\u00e0<\/strong>, per costruirne le relazioni pi\u00f9 semplici: dentro o fuori, rumore confuso della citt\u00e0 e luogo urbano dove mettere in scena la rappresentazione pi\u00f9 semplice dell\u2019arte moderna e dell\u2019arte contemporanea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La megalopoli si avviluppa dentro la concretezza del cemento, rosso, come per volersi allontanare da ogni contesto, un recinto sacro per dare vita al mondo casuale che lo attraversa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il MASP \u00e8 vivo, si trasforma, respira diventa l\u2019architettura potenziale<\/strong>, il recinto magico dove ascoltare il suono arcaico e contemporaneo dell\u2019arte del mondo: un amplificatore di bellezza che regala ad ogni istante, la natura stessa del nostro esistere.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/03_Sesc-Pompe\u0301ia.-Image-\u00a9-Pedro-Kok.jpg\" alt=\"Lina Bo Bardi\" class=\"wp-image-9518\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/03_Sesc-Pompe\u0301ia.-Image-\u00a9-Pedro-Kok.jpg 1000w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/03_Sesc-Pompe\u0301ia.-Image-\u00a9-Pedro-Kok-300x300.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/03_Sesc-Pompe\u0301ia.-Image-\u00a9-Pedro-Kok-150x150.jpg 150w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/03_Sesc-Pompe\u0301ia.-Image-\u00a9-Pedro-Kok-768x768.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/03_Sesc-Pompe\u0301ia.-Image-\u00a9-Pedro-Kok-500x500.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Sesc Pomp\u00e9ia. Image \u00a9 Pedro Kok<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il Brasile di Lina \u00e8 la metafora del mondo<\/strong>, la grandezza delle nostre essenzialit\u00e0, il punto esatto dove abbiamo deciso di fondere oriente e occidente, passato e futuro, adesso e mai, per questo i musicisti tropicalisti la spiano da lontano, Gilberto Gil, Caetano Veloso e gli altri l\u2019adorano, ma non hanno il coraggio di fermarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lei vuole pezzi di citt\u00e0 da trasformare in spazi pubblici<\/strong>, in \u201cmomenti senza costo\u201d, piazze coperte, e tavolini, ragazze col tut\u00f9 e grandi vecchi che estinguono le loro giornate inventando strategie per gli scacchi, teatri, mense popolari, <strong>momenti nati per esprimere il calore dell\u2019arte che pulsa in quell\u2019istante<\/strong>, e che libera di tutte le paure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LEGGI ANCHE &#8211; <a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\">Penthouse One-11: la sinuosa torre di comando Zaha Hadid a Citylife<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>San Salvador de Bahia \u00e8 troppo lontana da San Paolo<\/strong>, e le carcasse delle fabbriche abbandonate possono raccontare gli istanti che hanno l\u2019aspetto di un nuovo urbanesimo romantico, colorato e caldissimo, la fonte delle nostre possibilit\u00e0, la grandezza di un\u2019idea che deve ricordare, che sente il cuore, ascolta il flusso irregolare della citt\u00e0, dove ci ritroviamo naturalmente per costruire relazioni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019architettura di Lina Bo Bardi<\/strong>, \u00e8 la prova necessaria di conservare quella bellezza per l\u2019umanit\u00e0, per renderla patrimonio degli uomini, nel XX o in tutti i secoli precedenti, per raccontare il significato del nostro stare qui, ed ora ed in questo momento, quando progettare aveva ancora un senso antropologico, e gli uomini si ri-trovavano per raccontare e raccontarsi lo Spazio e le Storie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ASCOLTA LA PUNTATA DI DANNATI ARCHITETTI SU LINA BO BARDI<\/strong><\/p>\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/widget.spreaker.com\/player?episode_id=41771449&amp;theme=light&amp;playlist=false\" width=\"100%\" height=\"200px\" frameborder=\"0\"><\/iframe>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Sembra avere tanto tempo (e poi il tempo che cosa rappresenta, in quella parte del mondo?), vecchie fabbriche da trasformare, teatri, mostre, allestimenti e una corsa verso un tavolo da disegno dove trovare qualcosa che assomigli ad una soluzione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Architetta fino in fondo, donna incapace di frenare la sua irragionevole volont\u00e0 di produrre stupore, di realizzare sogni condivisi, di superare limiti e teorie fino a costruire una personale, personalissima idea di citt\u00e0, fatta pochi luoghi essenziali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Come nei suoi disegni gentili, delicati ed essenziali, tanto ammirati nel mondo e conservati nella casa di vetro, oggi avviluppata dall\u2019incontrollabile vegetazione e nell\u2019immutata forza razionalista, paulista, oggi catalogati a migliaia da archivisti solerti e preziosi (oltre 7500). <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina_Bo_Bardi_SESC_Pompe\u0301ia._8736296851-1024x768.jpg\" alt=\"Lina Bo Bardi, SESC Pomp\u00e9ia\" class=\"wp-image-9520\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina_Bo_Bardi_SESC_Pompe\u0301ia._8736296851-1024x768.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina_Bo_Bardi_SESC_Pompe\u0301ia._8736296851-300x225.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina_Bo_Bardi_SESC_Pompe\u0301ia._8736296851-768x576.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina_Bo_Bardi_SESC_Pompe\u0301ia._8736296851-1536x1152.jpg 1536w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina_Bo_Bardi_SESC_Pompe\u0301ia._8736296851-2048x1536.jpg 2048w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina_Bo_Bardi_SESC_Pompe\u0301ia._8736296851-500x375.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Lina Bo Bardi, SESC Pomp\u00e9ia<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Questa \u00e8 un\u2019altra donna che abbiamo ammirato per l\u2019eleganza, la forza, l\u2019spirazione cristallina e la potenza del gesto, <strong>\u201dDonna Lina\u201d ha costruito dall\u2019altra parte del mondo, la sua precisa idea di estetica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ha voluto regalare all\u2019architettura una diversa concezione politica, culturale solo per dare contenuti nuovi ad una pratica antica<\/strong>, per portarci un pi\u00f9 lontano, dove l\u2019emozione, la passione e l\u2019amore possono restituirci nuova vita, nuovi colori, un\u2019idea diversa di socialit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sua missione \u00e8 compiuta, ma comunque breve, ha avuto il tempo Lina Bo, di ricordare <strong>\u201cla tavola degli orrori\u201d, dove <a href=\"https:\/\/it.wikipedia.org\/wiki\/Pietro_Maria_Bardi\" target=\"_blank\" aria-label=\"undefined (apri in una nuova scheda)\" rel=\"noreferrer noopener\">Pietro Maria Bardi<\/a> ha raccontato sinteticamente la negazione della ricerca<\/strong>, le ha ispirato il tracciato verso l\u2019essenza della progettazione, verso la natura essenziale di quel nuovo mondo, dove ragione e sentimento si re-incontrano nelle forme pi\u00f9 pure, quelle uniche che non riusciremo mai a dimenticare.<\/p>\n\n\n\n<div class=\"wp-block-group has-very-light-gray-color has-very-dark-gray-background-color has-text-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"h-la-tavola-degli-orrori-alla-mostra-d-architettura-razionale\">La \u201cTavola degli orrori\u201d alla Mostra d\u2019Architettura Razionale<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ecco la cosiddetta \u201cTavola degli Orrori\u201d esposta alla Mostra di Architettura Razionale attualmente aperta alla Galleria di Roma in via Veneto. Nel rimetterci questa fotografia P. M. Bardi, direttore della Galleria stessa, unisce il seguente trafiletto nel quale sono spiegati gli intenti polemici della composizione:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ad un certo momento del secolo scorso, quando dell\u2019idea architettonica s\u2019era ormai perduto persino l\u2019odore, nacque l\u2019architetto culturalista. Nacque forse nel botteghino d\u2019un rivendugliolo di stampe antiche, da padre eclettico e da madre accomodatutto. Crebbe il piccino con il latte di cento balie, ed alla scuola con le lezioni di cento precettori: aveva il ragazzo da impluteare nella zucca un\u2019enciclopedia di nozioni architettoniche, poich\u00e9 l\u2019angiolo aveva svelato ai genitori in sogno che il loro parto avrebbe avuto il ruolo, nel secolo, di architetto culturalista.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/tavola-degli-orrori-Pier-Maria-Bardi-1024x703.jpg\" alt=\"\u201cTavola degli Orrori\u201d P M Bardi\" class=\"wp-image-9529\" srcset=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/tavola-degli-orrori-Pier-Maria-Bardi-1024x703.jpg 1024w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/tavola-degli-orrori-Pier-Maria-Bardi-300x206.jpg 300w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/tavola-degli-orrori-Pier-Maria-Bardi-768x527.jpg 768w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/tavola-degli-orrori-Pier-Maria-Bardi-500x343.jpg 500w, https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/tavola-degli-orrori-Pier-Maria-Bardi.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Conoscere: fu questo il motto che il giovinetto incise nel suo ex-libris. Comporre: fu questo l\u2019impegno ch\u2019egli si assunse di fronte al prossimo. Erigere delle case: fu questo l\u2019incarico che l\u2019attonita borghesia, fiduciosa di lui, affid\u00f2 al nuovo leone. Giorni memorabili trascorse l\u2019annunciatore in mezzo alle citt\u00e0, con la letizia dell\u2019uffizio adempiuto con quella seriet\u00e0 di propositi che conduce alle soglie del paradiso. Ogni uomo ha nel capo il suo paradiso, composto delle sue preferenze ideali, dei suoi amori, delle sue sottili e godute conquiste morali. E l\u2019architetto culturalista ebbe il suo paradiso: non se ne ebbe mai la chiave di quel limbo misterioso e pochi, pochissimi indagatori riuscirono a penetrare in qualcuna delle camere d\u2019aspetto del complicato labirinto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La storia del gusto, per suo conto, indag\u00f2 a pi\u00f9 non posso per rivelare quel patetico mondo del tipo assunto ormai alle celebrit\u00e0 incontrovertibili: ma fu tempo perduto. Abbiamo, oggi, noi il privilegio di svelare quel segreto: \u00e8 andata cos\u00ec: abbiamo ammazzato l\u2019architetto culturalista, gli abbiamo aperto il cranio, ed abbiamo accuratamente ricavato tutto il suo paradiso. Lo abbiamo ricomposto minuziosamente e fotografato, per darne notizia accurata ai nostri lettori. Ecco, finalmente, di che si tratta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P. M. Bardi<\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\t\r\n\t\t\t\t\t\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\"><strong>Seguici sui nostri canali per restare sempre aggiornato: <\/strong><\/p>\n\n\n\n<ul class=\"has-white-color has-black-background-color has-text-color has-background has-link-color wp-block-list wp-elements-22151444a665cce6c776750adbab5190\">\n<li><a href=\"https:\/\/t.me\/listonegiordanoofficial\">Canale Telegram<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/whatsapp.com\/channel\/0029VaR7wuhCnA7pPd7rte40\">Canale Whatsapp<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.instagram.com\/listonegiordano\/\">Instagram <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.facebook.com\/listonegiordanoitalia\">Facebook<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.linkedin.com\/company\/listone-giordano\">Linkedin<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\t\t<div class=\"related-posts\">\r\n\t\t\t<h3 class=\"lusitana medium-font green roboto align-center row-padding\"><span>Related Articles<\/span><\/h3>\r\n\t\t\t<div class=\"container white-bkg\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/nel-cielo-stellato-di-zaha-hadid\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/zaha-hadid-science-museum-500x281.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/\">Maurizio De Caro<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/nel-cielo-stellato-di-zaha-hadid\/\" rel=\"bookmark\">Nel cielo stellato di  Zaha Hadid<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/donne-e-architettura-qualche-secolo-di-discriminazioni-derisioni-incomprensioni-isolamenti-e-luoghi-comuni\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/06\/Plautilla-Bricci-melania-mazzucco-1.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/\">Maurizio De Caro<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/donne-e-architettura-qualche-secolo-di-discriminazioni-derisioni-incomprensioni-isolamenti-e-luoghi-comuni\/\" rel=\"bookmark\">Donne e architettura, qualche secolo di discriminazioni, derisioni, incomprensioni, isolamenti e luoghi comuni<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"separator-mobile clear\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/citylife_zaha_hadid_woodfloor-40-1-500x333.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/t-plan\/\">The Plan<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/penthouse-one-11\/\" rel=\"bookmark\">Penthouse One-11: la sinuosa torre di comando Zaha Hadid a Citylife<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"regular-article column-of-4 left col-padding row-padding\">\r\n\t\t\t\t\t\t<a class=\"image not-mobile\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/la-rivincita-dei-trentenni-la-normalita-dellarchitettura\/\" rel=\"bookmark\"><img decoding=\"async\" class=\"cover\" src=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/04\/biro-borgo-parelios-13-500x269.jpg\" loading=\"lazy\"><\/a>\r\n\t\t\t\t\t\t<div class=\"postedby-on roboto tiny-font\">\t<span class=\"lower byline\">di<\/span> <span class=\"byline\"><span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.listonegiordano.com\/one\/author\/debora\/\">Debora Vella<\/a><\/span><\/span>\t<span class=\"posted-on\"> &#8211; 6 anni fa<\/span><\/div>\t\t\t\t\t\t<h2 class=\"title lusitana small-font\"><a href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/la-rivincita-dei-trentenni-la-normalita-dellarchitettura\/\" rel=\"bookmark\">La rivincita dei trentenni, la normalit\u00e0 dell&#8217;architettura<\/a><\/h2>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<br class=\"clear\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica, un progetto esistenziale, sentimentale e professionale [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":9611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"area":"","groups":"","preview":"","columns":"","rows":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-9502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura"],"featured_image_src":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946-150x150.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lina Bo Bardi, &quot;il Brasile \u00e8 il paese dove voglio vivere&quot; | One Listone Giordano<\/title>\n<meta name=\"description\" content=\"Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica come Lina Bo Bardi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lina Bo Bardi, &quot;il Brasile \u00e8 il paese dove voglio vivere&quot;\" \/>\n<meta property=\"og:description\" content=\"Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica, un progetto esistenziale, sentimentale e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/\" \/>\n<meta property=\"og:site_name\" content=\"One Listone Giordano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/listonegiordanoitalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-05T13:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-16T16:55:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2257\" \/>\n\t<meta property=\"og:image:height\" content=\"1195\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maurizio De Caro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maurizio De Caro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/\"},\"author\":{\"name\":\"Maurizio De Caro\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\"},\"headline\":\"Lina Bo Bardi, &#8220;il Brasile \u00e8 il paese dove voglio vivere&#8221;\",\"datePublished\":\"2020-08-05T13:30:24+00:00\",\"dateModified\":\"2021-02-16T16:55:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/\"},\"wordCount\":2027,\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg\",\"articleSection\":[\"Architettura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/\",\"name\":\"Lina Bo Bardi, \\\"il Brasile \u00e8 il paese dove voglio vivere\\\" | One Listone Giordano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg\",\"datePublished\":\"2020-08-05T13:30:24+00:00\",\"dateModified\":\"2021-02-16T16:55:30+00:00\",\"description\":\"Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica come Lina Bo Bardi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg\",\"width\":2257,\"height\":1195,\"caption\":\"Lina Bo Bardi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/architettura\\\/lina-bo-bardi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lina Bo Bardi, &#8220;il Brasile \u00e8 il paese dove voglio vivere&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#website\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"name\":\"One Listone Giordano\",\"description\":\"Il magazine sull&#039;Architettura e Design firmato Listone Giordano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#organization\",\"name\":\"One Listone Giordano\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/MLG-19-immagine_profilo_redazione-1.jpg\",\"width\":900,\"height\":600,\"caption\":\"One Listone Giordano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/listonegiordanoitalia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/listonegiordano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/listone-giordano\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/listoneg\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ListoneGiordano01\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Listone_Giordano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/#\\\/schema\\\/person\\\/e68e8dc996646f715eaeadfdbb979481\",\"name\":\"Maurizio De Caro\",\"description\":\"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\\\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net\",\"url\":\"https:\\\/\\\/www.listonegiordano.com\\\/one\\\/author\\\/decaro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lina Bo Bardi, \"il Brasile \u00e8 il paese dove voglio vivere\" | One Listone Giordano","description":"Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica come Lina Bo Bardi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/","og_locale":"it_IT","og_type":"article","og_title":"Lina Bo Bardi, \"il Brasile \u00e8 il paese dove voglio vivere\"","og_description":"Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica, un progetto esistenziale, sentimentale e","og_url":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/","og_site_name":"One Listone Giordano","article_publisher":"https:\/\/www.facebook.com\/listonegiordanoitalia\/","article_published_time":"2020-08-05T13:30:24+00:00","article_modified_time":"2021-02-16T16:55:30+00:00","og_image":[{"width":2257,"height":1195,"url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg","type":"image\/jpeg"}],"author":"Maurizio De Caro","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maurizio De Caro","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/#article","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/"},"author":{"name":"Maurizio De Caro","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481"},"headline":"Lina Bo Bardi, &#8220;il Brasile \u00e8 il paese dove voglio vivere&#8221;","datePublished":"2020-08-05T13:30:24+00:00","dateModified":"2021-02-16T16:55:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/"},"wordCount":2027,"publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg","articleSection":["Architettura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/","url":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/","name":"Lina Bo Bardi, \"il Brasile \u00e8 il paese dove voglio vivere\" | One Listone Giordano","isPartOf":{"@id":"https:\/\/www.listonegiordano.com\/one\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/#primaryimage"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg","datePublished":"2020-08-05T13:30:24+00:00","dateModified":"2021-02-16T16:55:30+00:00","description":"Nessuna donna nella storia dell\u2019architettura italiana del XX secolo ha mai raggiunto un\u2019iconicit\u00e0 teorica come Lina Bo Bardi.","breadcrumb":{"@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/#primaryimage","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2020\/08\/Lina-Bo-Bardi-on-the-ship-Almirante-Jaceguay-on-her-way-to-Brasil-in-1946.jpg","width":2257,"height":1195,"caption":"Lina Bo Bardi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.listonegiordano.com\/one\/architettura\/lina-bo-bardi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.listonegiordano.com\/one\/"},{"@type":"ListItem","position":2,"name":"Lina Bo Bardi, &#8220;il Brasile \u00e8 il paese dove voglio vivere&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.listonegiordano.com\/one\/#website","url":"https:\/\/www.listonegiordano.com\/one\/","name":"One Listone Giordano","description":"Il magazine sull&#039;Architettura e Design firmato Listone Giordano","publisher":{"@id":"https:\/\/www.listonegiordano.com\/one\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.listonegiordano.com\/one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.listonegiordano.com\/one\/#organization","name":"One Listone Giordano","url":"https:\/\/www.listonegiordano.com\/one\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/","url":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","contentUrl":"https:\/\/www.listonegiordano.com\/one\/wp-content\/uploads\/2019\/08\/MLG-19-immagine_profilo_redazione-1.jpg","width":900,"height":600,"caption":"One Listone Giordano"},"image":{"@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/listonegiordanoitalia\/","https:\/\/www.instagram.com\/listonegiordano\/","https:\/\/www.linkedin.com\/company\/listone-giordano\/","https:\/\/www.pinterest.it\/listoneg","https:\/\/www.youtube.com\/user\/ListoneGiordano01","https:\/\/it.wikipedia.org\/wiki\/Listone_Giordano"]},{"@type":"Person","@id":"https:\/\/www.listonegiordano.com\/one\/#\/schema\/person\/e68e8dc996646f715eaeadfdbb979481","name":"Maurizio De Caro","description":"Maurizio de Caro, architetto,ha studiato a Milano (Politecnico, Facolt\u00e0 di architettura) e Londra (Architectural Association) Musicofilo, giornalista, collezionista d\u2019Arte Contemporanea, teorico dell\u2019architettura, gi\u00e0 docente di Estetica alla Facolt\u00e0 di Architettura del Politecnico di Milano. Consigliere dell'Ordine degli Architetti della Provincia di Milano(2009-2013) Presidente della Fondazione Colore di Lissone(MB) Consigliere d\u2019Amministrazione del Museo Bagatti Valsecchi,Milano Ha scritto saggi per Electa, Fabbri Editore, LIndau,il Clavicembalo, ha collaborato col Corriere della Sera, Il Sole24ore, La Stampa, il Riformista etc.), attualmente editorialista di affari Italiani.it. e ONE(Listone Giordano) Tra i progetti:La metropolitana leggera Cascina Gobba\/H.San Raffaele Coordina il gruppo di progettazione per la realizzazione delle Architetture di Servizio di Expo Milano 2015 Dal 2018 \u00e8 art director di Krill Design Vive e lavora a Milano(attraverso le tre societ\u00e0 Maurizio de Caro Architects &amp; Planners, @deCaroArchitects e The factory of matter, che si occupano di ricerca, comunicazione culturale, allestimenti e progettazione integrata) www.mauriziodecaro.net","url":"https:\/\/www.listonegiordano.com\/one\/author\/decaro\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/9502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/comments?post=9502"}],"version-history":[{"count":20,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/9502\/revisions"}],"predecessor-version":[{"id":12678,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/posts\/9502\/revisions\/12678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media\/9611"}],"wp:attachment":[{"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/media?parent=9502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/categories?post=9502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.listonegiordano.com\/one\/wp-json\/wp\/v2\/tags?post=9502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}